<!---->{"id":1017,"date":"2020-08-31T00:00:00","date_gmt":"2020-08-30T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/el-cloro-de-las-piscinas-una-sustancia-que-puede-ser-perjudicial-para-los-usuarios-de-lentes-de-contacto\/"},"modified":"2023-01-18T01:32:18","modified_gmt":"2023-01-18T00:32:18","slug":"el-cloro-de-las-piscinas-una-sustancia-que-puede-ser-perjudicial-para-los-usuarios-de-lentes-de-contacto","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/el-cloro-de-las-piscinas-una-sustancia-que-puede-ser-perjudicial-para-los-usuarios-de-lentes-de-contacto\/","title":{"rendered":"El cloro de las piscinas, una sustancia que puede ser perjudicial para los usuarios de lentes de contacto"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">swim-422546_1920.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/AC7E6CA0-007A-4CFC-84EB-DA0A362DC350\/Cuerpo\/swim-422546_1920.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>En verano aparecen algunos de los principales enemigos de los ojos, ya que las exposiciones prolongadas al sol, la arena y las alergias son causantes esenciales de muchos efectos perjudiciales. En el caso que nos ba\u00f1emos en piscinas no hay que olvidar, que el sistema de desinfecci\u00f3n empleado com\u00fanmente  es la adici\u00f3n de cloro al agua   para mantener  a esta  libre de organismos  pat\u00f3genos.\n<\/p>\n<p>El mal uso y regulaci\u00f3n de las cantidades de este producto  puede jugar un papel en nuestra contra, ya que puede provocar irritaci\u00f3n en los ojos y dar lugar a la aparici\u00f3n de conjuntivitis y otras enfermedades oculares. Por eso, los usuarios de lentes de contacto tienen que tener much\u00edsimo cuidado al ba\u00f1arse en las piscinas  en las que no tengamos seguridad de una buena regulaci\u00f3n  de su mantenimiento y puesta a punto para evitar tanto contaminarlas , como perderlas.<\/p>\n<p>Desde la Fundaci\u00f3n Salud Visual (<a href=\"https:\/\/www.funsavi.es\/inicio\" target=\"_blank\" rel=\"noopener\">Funsavi<\/a>) te contamos cu\u00e1les son los problemas a los que te puedes enfrentar si utilizas lentillas en piscinas donde la cantidad de cloro y su pH no esta bien regulado:<\/p>\n<p><strong>&#8211;\t<\/strong><strong>Aparici\u00f3n de queratitis.<\/strong> Esta afecci\u00f3n puede estar causada por el contacto de las lentillas con soluciones no est\u00e9riles, por eso, para impedir su manifestaci\u00f3n es fundamental no sumergirse en el agua con las lentes puestas, ni ducharse con ellas, pues adem\u00e1s se pueden perder Se pueden utilizar gafas de bucear sin prescindir de las lentes, pero hay que tener en cuenta que incluso con las gafas puestas puede entrar agua, por tanto, no es recomendable su uso. <\/p>\n<p><strong>&#8211;\tEscozor de ojos y conjuntivitis al\u00e9rgica. <\/strong>Las piscinas tienen que estar correctamente aireadas  con una concentraci\u00f3n de cloro que mantenga el agua sin pat\u00f3genos y con un pH  de valores comprendidos entre 7.2 y 7,6  considerados valores id\u00f3neos para que las personas con tejidos conjuntivos m\u00e1s sensibles no se vean afectadas y sufran quemaz\u00f3n e irritaci\u00f3n de los p\u00e1rpados. Es cierto, que el culpable de que ocurran estos efectos da\u00f1inos no es \u00fanicamente el cloro sino la mezcla de esta sustancia con la saliva, el sudor e incluso, la orina de algunos ba\u00f1istas. El nitr\u00f3geno de los fluidos se mezcla con el cloro y se produce una sustancia t\u00f3xica que es la causante de la irritaci\u00f3n. <\/p>\n<p><span style=\"text-decoration: underline;\">Para evitar estos problemas deber\u00edas:<br \/>\n<\/span><\/p>\n<p>&#8211;\tUtilizar la ducha antes del ba\u00f1o y despu\u00e9s de salir de la piscina para eliminar el sudor y los residuos en la piel. <\/p>\n<p>&#8211;\tNo hacer uso de toallas ajenas.<\/p>\n<p>&#8211;\tEvitar frotar los ojos al salir de la piscina.<\/p>\n<p>&#8211;\tLavar bien las manos antes y despu\u00e9s de ponerte las lentillas.<\/p>\n<p>&#8211;\tUsar gafas de sol homologadas y que protejan al 100% de los rayos ultravioleta.<\/p>\n<p>&#8211;\tEnjuagar los ojos con suero fisiol\u00f3gico. <\/p>\n<p>&#8211;\tNo usar las lentes m\u00e1s de 8 o 10 horas al d\u00eda. <\/p>\n<p>&#8211;\tLlevar l\u00e1grimas artificiales para aliviar las molestias causadas por la sequedad ocular. <\/p>\n<p>&#8211;\tNo ba\u00f1arte en la piscina si huele muy fuerte a cloro. <\/p>\n<p>Hay que tener en cuenta que el uso de lentillas en la piscina aumenta el riesgo de su  contaminaci\u00f3n, por lo que es fundamental mantener una buena higiene y a ser posible prescindir de su uso.<br \/>\n<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/AC7E6CA0-007A-4CFC-84EB-DA0A362DC350\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Os ofrecemos una serie de consejos para evitar los problemas visuales e inconvenientes derivados del cloro de las piscinas.<\/p>\n","protected":false},"featured_media":1841,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-1017","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/1017","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1841"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=1017"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=1017"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=1017"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}