<!---->{"id":1038,"date":"2016-08-25T00:00:00","date_gmt":"2016-08-24T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/la-forma-de-evitar-la-fatiga-visual-en-la-jornada-laboral\/"},"modified":"2023-01-18T01:45:07","modified_gmt":"2023-01-18T00:45:07","slug":"la-forma-de-evitar-la-fatiga-visual-en-la-jornada-laboral","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/la-forma-de-evitar-la-fatiga-visual-en-la-jornada-laboral\/","title":{"rendered":"La forma de evitar la fatiga visual en la jornada laboral"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">shutterstock_1619714.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/EDD5BF98-6C32-43C5-AE46-E3C7B07F6D22\/Cuerpo\/shutterstock_1619714.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>Por ejemplo, en relaci\u00f3n a la posici\u00f3n delante del ordenador, que la direcci\u00f3n de los ojos coincida con la parte superior de la pantalla, y a una distancia entre 55 y 60 cm.<\/p>\n<p>La secretaria general del COOCYL, Ana Bel\u00e9n Cisneros, recomienda la regla del 20, es decir, \u201ccada 20 minutos levantar la vista durante 20 segundos mirando a 20 pies o 6 metros para relajar la visi\u00f3n\u201d, y como a\u00f1ade, tambi\u00e9n es importante \u201cque se relaje la visi\u00f3n al hacer una tarea de cerca de forma continuada\u201d.<br \/>Sequedad ocular<\/p>\n<p>El delegado del Colegio en Salamanca, Mariano Luengo S\u00e1nchez, insiste en que son dos los problemas oculares asociados al uso del ordenador: la fatiga y la sequedad ocular. \u201cHay que recordar que el ojo se encuentra controlado por m\u00fasculos y como tales deben ser sometidos a unas pautas que no nos lleven a un sobreesfuerzo que provoque ese inc\u00f3modo cansancio que condiciona nuestro trabajo\u201d, subraya.<\/p>\n<p>Adem\u00e1s, Luengo recuerda que cuando se est\u00e1 concentrado en una actividad de cerca, \u201cel ritmo de parpadeo disminuye pero tambi\u00e9n es cierto que si trabajamos en un ambiente demasiado seco provocado por el sistema de calefacci\u00f3n-refrigeraci\u00f3n, que tambi\u00e9n motivar\u00e1 una sensaci\u00f3n inc\u00f3moda al notar un d\u00e9ficit de l\u00e1grima, por lo que en esos casos ser\u00eda conveniente recurrir a alg\u00fan tipo de hidratante ocular\u201d.<br \/>Iluminaci\u00f3n<\/p>\n<p>Los \u00f3pticos-optometristas de Castilla y Le\u00f3n insisten tambi\u00e9n en cuidar la iluminaci\u00f3n en el espacio de trabajo, y lo ideal es la luz natural, y de no ser as\u00ed, que sea uniforme, que no provoque sombras marcadas sobre el plano de trabajo y que garantice unos niveles adecuados. Asimismo, es importante evitar cualquier deslumbramiento o reflejo en la pantalla, mesa, teclado u ojos del usuario, producido por luz natural o artificial.<\/p>\n<p>Si tras seguir los consejos para evitar la fatiga visual siguen las molestias, \u201ces de suma importancia hacer un estudio personalizado, ya que a veces la visi\u00f3n es buena pero los ojos no est\u00e1n funcionando correctamente (no funcionan de la mejor forma binocular posible o no se coordinan bien)\u201d.<\/p>\n<p><\/p>\n<p>    PAUTAS PARA CUIDAR TUS OJOS<\/p>\n<ul>\n<li><span id=\"sbm\"><\/span><span id=\"sbm\"><\/span><span id=\"sbm\"><\/span><span id=\"sbm\"><\/span><span id=\"sbm\"><\/span><span id=\"sbm\"><\/span>Cada 15-20 minutos se deber\u00e1n hacer cambios de mirada cerca-lejos para relajar la visi\u00f3n, y cada 1 \u00f3 2 horas es necesario interrumpir el trabajo, descansar y levantarse.<\/li>\n<li>        El teclado ser\u00e1 inclinable e independiente de la pantalla y su superficie ser\u00e1 mate.<\/li>\n<li>        La pantalla tiene que colocarse perpendicular a las ventanas, que estar\u00e1n provistas de cortinas que tamicen y aten\u00faen la luz.<\/li>\n<li>        La temperatura ambiental estar\u00e1 entre los 23\u00ba y 26\u00ba, seg\u00fan la \u00e9poca del a\u00f1o, con una humedad relativa del 50%.<\/li>\n<li>        El asiento ser\u00e1 estable, giratorio, con respaldo inclinable y apoyo lumbar. Es conveniente el uso de un reposapi\u00e9s.<\/li>\n<\/ul>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/EDD5BF98-6C32-43C5-AE46-E3C7B07F6D22\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Las personas que se pasan muchas horas frente a la pantalla de un ordenador suelen notar frecuentemente molestias como la irritaci\u00f3n de ojos, los dolores oculares y de cabeza, el picor de ojos, el deslumbramiento o el lagrimeo.<br \/>Desde el Colegio de \u00d3pticos-Optometristas de Castilla y Le\u00f3n (COOCYL)  insisten en una serie de consejos para evitar la fatiga visual y mejorar su calidad de vida en este sentido.<\/p>\n","protected":false},"featured_media":1860,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-1038","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/1038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1860"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=1038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=1038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=1038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}