<!---->{"id":1076,"date":"2018-01-29T00:00:00","date_gmt":"2018-01-28T23:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/un-estudio-halla-un-vinculo-genetico-entre-las-corneas-mas-delgadas-y-el-aumento-del-riesgo-de-glaucoma\/"},"modified":"2023-01-18T01:46:50","modified_gmt":"2023-01-18T00:46:50","slug":"un-estudio-halla-un-vinculo-genetico-entre-las-corneas-mas-delgadas-y-el-aumento-del-riesgo-de-glaucoma","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/un-estudio-halla-un-vinculo-genetico-entre-las-corneas-mas-delgadas-y-el-aumento-del-riesgo-de-glaucoma\/","title":{"rendered":"Un estudio halla un v\u00ednculo gen\u00e9tico entre las c\u00f3rneas m\u00e1s delgadas y el aumento del riesgo de glaucoma"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">human-eye-995168_128.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/F41872E5-9262-4DF6-A58E-FE620E257559\/Cuerpo\/human-eye-995168_128.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>El glaucoma comprende un grupo de enfermedades oculares que causan presi\u00f3n que se acumula en el ojo, lo que da\u00f1a el nervio \u00f3ptico y finalmente conduce a la ceguera. M\u00faltiples factores de riesgo y mutaciones subyacentes contribuyen al glaucoma, pero el factor de riesgo m\u00e1s conocido es tener una c\u00f3rnea delgada; por lo que Geisert y sus colegas investigaron genes que afectan al grosor corneal utilizando cepas de ratones.\n<\/p>\n<p>Despu\u00e9s, compararon variantes gen\u00e9ticas que conducen a c\u00f3rneas delgadas en ratones con genes que aumentan el riesgo de una persona de un tipo com\u00fan de glaucoma, llamado glaucoma primario de \u00e1ngulo abierto. Los autores identificaron un factor de transcripci\u00f3n llamado POU6F2, que se encuentra en el desarrollo de c\u00e9lulas nerviosas en la retina y las c\u00e9lulas corneales en ratones.<\/p>\n<p>Cuando eliminaron el gen que codifica POU6F2, los ratones afectados presentaban c\u00f3rneas m\u00e1s delgadas que los roedores normales. Adem\u00e1s, POU6F2 parece ayudar a regular la c\u00f3rnea en desarrollo y tambi\u00e9n puede ser responsable, en parte, de mantener sana la c\u00f3rnea al regular las c\u00e9lulas madre de la c\u00f3rnea en ratones adultos.<\/p>\n<p>En general, el nuevo trabajo sugiere que las variaciones gen\u00e9ticas en el gen que codifica POU6F2 pueden afectar a la estructura del ojo e incrementar el riesgo de glaucoma de una persona, pero se necesitar\u00e1n estudios adicionales para describir el mecanismo exacto.<\/p>\n<p><strong>EN BUSCA DE UN V\u00cdNCULO GEN\u00c9TICO ENTRE GLAUCOMA Y C\u00d3RNEAS DELGADAS<\/strong><\/p>\n<p>Encontrar un v\u00ednculo gen\u00e9tico entre el glaucoma y las c\u00f3rneas delgadas ha sido dif\u00edcil porque, aunque ambos rasgos se presentan en familias, contribuyen a estos rasgos complejos una combinaci\u00f3n complicada de genes m\u00faltiples y condiciones ambientales. Sin embargo, el papel de POU6F2 en el desarrollo de la c\u00f3rnea y el grosor en ratones apunta al gen como un posible factor de riesgo para el glaucoma en humanos que merece mayor investigaci\u00f3n.<\/p>\n<p>El doctor Geisert se\u00f1ala: &quot;El glaucoma es una enfermedad compleja con muchos factores gen\u00e9ticos y ambientales que influyen en la poblaci\u00f3n de pacientes. El trabajo previo de colaboradores de Harvard y Duke identific\u00f3 muchos de estos factores gen\u00e9ticos, sin embargo, actualmente solo podemos representar aproximadamente el 7 por ciento del riesgo gen\u00e9tico para el glaucoma&quot;.<\/p>\n<p>&quot;Elegimos utilizar un sistema de rat\u00f3n bien definido para identificar los elementos gen\u00e9ticos que pueden estar directamente vinculados con la enfermedad humana. Esperamos que la definici\u00f3n de este v\u00ednculo entre el grosor corneal central y el glaucoma ayude a la detecci\u00f3n temprana del glaucoma y eventualmente a tratamientos para detener la progresi\u00f3n de esta enfermedad&quot;, concluye.<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/F41872E5-9262-4DF6-A58E-FE620E257559\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estudios gen\u00e9ticos en ratones apuntan a una prote\u00edna llamada POU6F2, que puede modular el grosor corneal, como un posible factor de riesgo para el glaucoma en humanos, seg\u00fan informan este jueves en &#8216;PLOS Genetics&#8217; Eldon Geisert, de la Universidad de Emory, en Atlanta, Georgia, Estados Unidos, y sus colegas.<\/p>\n","protected":false},"featured_media":1898,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-1076","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/1076","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1898"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=1076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=1076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=1076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}