<!---->{"id":18666,"date":"2016-12-21T01:39:00","date_gmt":"2016-12-21T00:39:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/?post_type=informaciones&#038;p=18666"},"modified":"2023-05-18T01:47:28","modified_gmt":"2023-05-17T23:47:28","slug":"funsavi-hace-entrega-de-gafas-graduadas-a-refugiados-4","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/funsavi-hace-entrega-de-gafas-graduadas-a-refugiados-4\/","title":{"rendered":"FUNSAVI hace entrega de gafas graduadas a refugiados"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"166\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-content\/uploads\/sites\/7\/2023\/05\/FUNSAVI-hace-entrega-de-gafas-graduadas-a-refugiados-.jpeg\" alt=\"\" class=\"wp-image-18667\"\/><\/figure>\n\n\n\n<p>La Fundaci\u00f3n Salud Visual (FUNSAVI) en colaboraci\u00f3n con la Fundaci\u00f3n Deporte Integra ONGD celebr\u00f3, el pasado 15 de diciembre, la jornada de entrega de gafas para las m\u00e1s de 50 personas refugiadas, pertenecientes a diversos centros de la Confederaci\u00f3n Espa\u00f1ola de Atenci\u00f3n al Refugiado (CEA) y a la Asociaci\u00f3n de Apoyo al Pueblo Sirio (AAPS), que recibieron atenci\u00f3n de los \u00f3pticos-optometristas durante las Jornadas Cl\u00ednicas del Colegio Nacional de \u00d3pticos Optometristas.<br>La entrega de las gafas fue realizada por el secretario de FUNSAVI, Luis Alfonso Garc\u00eda y el presidente del Consejo General de Colegios de \u00d3pticos-Optometristas (CGCOO), Juan Carlos Mart\u00ednez Moral.<br>La participaci\u00f3n obtenida, tanto en las revisiones previas como en la entrega de gafas, demuestra la importancia de este tipo de iniciativas para los colectivos que se han visto obligados a abandonar sus lugares de residencia por diversos conflictos.<br>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado mes noviembre, se celebr\u00f3 en el Hotel NH Collection Madrid Eurobuilding, las Jornadas Cl\u00ednicas del Colegio Nacional de \u00d3pticos Optometristas donde un equipo de \u00f3pticos-optometristas voluntarios realizaron mediciones a personas refugiadas de la Comunidad de Madrid, comprometi\u00e9ndose con la entrega del material de lentes que necesiten todos los usuarios.<\/p>\n","protected":false},"featured_media":18667,"template":"","meta":{"_crosspost_to_1":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[53],"tags":[],"class_list":["post-18666","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-comunicados-area-profesional"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/18666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/18667"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=18666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=18666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=18666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}