<!---->{"id":18679,"date":"2016-07-07T12:09:00","date_gmt":"2016-07-07T10:09:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/?post_type=informaciones&#038;p=18679"},"modified":"2023-05-18T02:11:17","modified_gmt":"2023-05-18T00:11:17","slug":"opticos-optometristas-y-fede-unidos-para-mejorar-la-atencion-visual-de-las-personas-con-diabetes-4","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/opticos-optometristas-y-fede-unidos-para-mejorar-la-atencion-visual-de-las-personas-con-diabetes-4\/","title":{"rendered":"\u00d3pticos optometristas y FEDE, unidos para mejorar la atenci\u00f3n visual de las personas con diabetes"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"166\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-content\/uploads\/sites\/7\/2023\/05\/O\u0301pticos-optometristas-y-FEDE-unidos-para-mejorar-la-atencio\u0301n-visual-de-las-personas-con-diabetes-.jpeg\" alt=\"\" class=\"wp-image-18680\"\/><\/figure>\n\n\n\n<p>El presidente del Consejo General de Colegios de \u00d3pticos-Optometristas, CGCOO, Juan Carlos Mart\u00ednez Moral; el secretario de la Fundaci\u00f3n Salud Visual, FUNSAVI, Luis Alfonso Garc\u00eda; y el presidente de la Federaci\u00f3n Espa\u00f1ola de Diabetes (FEDE), Andoni Lorenzo, han firmado un convenio marco de colaboraci\u00f3n con el objeto de involucrar al \u00f3ptico-optometrista en la detecci\u00f3n de la diabetes y en el cuidado y revisiones peri\u00f3dicas de los pacientes con diabetes.<\/p>\n\n\n\n<p>El \u00f3ptico-optometrista, como profesional sanitario de la salud visual que es, est\u00e1 capacitado para informar y sensibilizar a la poblaci\u00f3n sobre la diabetes y sus consecuencias para la salud visual; as\u00ed como ayudar a detectar posibles patolog\u00edas visuales a trav\u00e9s del an\u00e1lisis diferencial de las personas con diabetes que, en caso necesario, ser\u00e1n remitidas al m\u00e9dico de atenci\u00f3n primaria.<\/p>\n\n\n\n<p>Para el presidente de FEDE, Andoni Lorenzo, &#8220;la firma de este convenio significa el compromiso decidido de FEDE con la detecci\u00f3n precoz y la prevenci\u00f3n de las complicaciones de la diabetes. Y para el colectivo al que representamos, para la concesi\u00f3n de este doble objetivo es clave la colaboraci\u00f3n de los profesionales de la salud visual. No debemos olvidar tampoco que los problemas de visi\u00f3n asociados a la diabetes a\u00fan son muy desconocidos entre la poblaci\u00f3n general; de hecho, 7 de cada 10 espa\u00f1oles desconocen que la retinopat\u00eda diab\u00e9tica y su principal complicaci\u00f3n, el edema macular diab\u00e9tico, puede tener consecuencias muy graves para los pacientes&#8221;.<\/p>\n\n\n\n<p>Seg\u00fan el presidente del CGCOO, Juan Carlos Mart\u00ednez Moral, \u201cel objetivo de la firma de este convenio es la sensibilizaci\u00f3n y detecci\u00f3n por parte de los \u00f3pticos-optometristas de las graves complicaciones oculares consecuencia de la diabetes, como es la retinopat\u00eda diab\u00e9tica y el edema macular, en los pacientes de riesgo que acuden a nuestros establecimientos sanitarios de \u00f3ptica. Obviamente, el objetivo \u00faltimo tanto de FEDE como del Consejo General es la reducci\u00f3n de pacientes afectados por esta grave dolencia retiniana y la prevenci\u00f3n de la misma a trav\u00e9s de la informaci\u00f3n rigurosa al paciente y el consejo profesional\u201d.<\/p>\n\n\n\n<p>Qui\u00e9nes somos<\/p>\n\n\n\n<p>FEDERACI\u00d3N ESPA\u00d1OLA DE DIABETES, FEDE, es el \u00f3rgano representativo del colectivo de personas con diabetes en Espa\u00f1a que, a d\u00eda de hoy, padecen cerca 6.000.000 de personas, para lo que cuenta con un total de 19 socios: 19 federaciones auton\u00f3micas de personas con diabetes, que agrupan a unas 150 asociaciones de personas con diabetes, distribuidas por todo el territorio nacional. Entre sus principales objetivos se encuentran defender los derechos de estas personas; contribuir al apoyo moral, f\u00edsico y educativo del colectivo; fomentar y apoyar la educaci\u00f3n diabetol\u00f3gica; promover la mejora de la asistencia sanitaria; prevenir, intervenir y detectar precozmente la diabetes, e impulsar y desarrollar el inter\u00e9s y el desarrollo de la investigaci\u00f3n. Para m\u00e1s informaci\u00f3n: http:\/\/www.fedesp.es.<\/p>\n\n\n\n<p>CONSEJO GENERAL DE COLEGIOS DE \u00d3PTICOS-OPTOMETRISTAS, CGCOO, es la Corporaci\u00f3n que re\u00fane a m\u00e1s de 16.000 \u00f3pticos-optometristas colegiados, ejercientes y no ejercientes, que representan a la profesi\u00f3n \u00f3ptico-optom\u00e9trica en los \u00e1mbitos estatal e internacional. http:\/\/www.cgcoo.es<\/p>\n\n\n\n<p>LA FUNDACI\u00d3N SALUD VISUAL, FUNSAVI, tiene como objetivo promover h\u00e1bitos preventivos para la mejora de la salud visual de la poblaci\u00f3n, as\u00ed como la formaci\u00f3n y actualizaci\u00f3n de los conocimientos del \u00f3ptico-optometrista, de tal modo que se reafirme como el m\u00e1ximo referente en este \u00e1mbito. El \u00e1nimo de la Fundaci\u00f3n es ofrecer un servicio para la sociedad trabajando de la mano con otras instituciones profesionales en la mejora de la salud visual de la sociedad. http:\/\/www.funsavi.es<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los colectivos de \u00f3pticos optometristas, Consejo General de Colegios de \u00d3pticos Optometristas (CGCOO) y la Fundaci\u00f3n Salud Visual (FUNSAVI) firman un convenio marco de colaboraci\u00f3n con la Federaci\u00f3n Espa\u00f1ola de Diabetes (FEDE) cuyo objetivo principal es promover la mejor atenci\u00f3n visual a los pacientes con diabetes.<\/p>\n","protected":false},"featured_media":18680,"template":"","meta":{"_crosspost_to_1":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[33],"tags":[],"class_list":["post-18679","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-notas-de-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/18679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/18680"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=18679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=18679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=18679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}