<!---->{"id":2330,"date":"2022-10-05T15:50:00","date_gmt":"2022-10-05T13:50:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/?post_type=informaciones&#038;p=2330"},"modified":"2023-03-27T15:53:49","modified_gmt":"2023-03-27T13:53:49","slug":"intervencion-dr-andres-gene-en-el-programa-de-la-sexta-que-me-pasa-doctor","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/intervencion-dr-andres-gene-en-el-programa-de-la-sexta-que-me-pasa-doctor\/","title":{"rendered":"Intervenci\u00f3n Dr Andr\u00e9s Gen\u00e9 en el programa de la Sexta \u201c\u00bfQu\u00e9 me pasa doctor?\u201d"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"ast-oembed-container\" style=\"height: 100%;\"><iframe loading=\"lazy\" title=\"\u00bfQu\u00e9 me pasa, doctor Programa 248\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/7pK28vmz3_A?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Intervenci\u00f3n del Dr Andr\u00e9s Gen\u00e9 en el programa de la Sexta \u201c\u00bfQu\u00e9 me pasa doctor?\u201d sobre el Libro Blanco de la salud visal 2022 editado por el Consejo General de Colegios de \u00d3pticos-Optometristas , Sociedad Espa\u00f1ola de Optometr\u00eda y la Fundaci\u00f3n Salud Visual<\/p>\n","protected":false},"featured_media":2333,"template":"","meta":{"_crosspost_to_1":false,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[38],"tags":[],"class_list":["post-2330","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-videos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/2330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/2333"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=2330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=2330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=2330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}