<!---->{"id":605,"date":"2018-04-14T00:00:00","date_gmt":"2018-04-13T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/estrategias-de-vision-simultanea-para-la-correccion-de-la-presbicia\/"},"modified":"2023-01-18T01:14:58","modified_gmt":"2023-01-18T00:14:58","slug":"estrategias-de-vision-simultanea-para-la-correccion-de-la-presbicia","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/estrategias-de-vision-simultanea-para-la-correccion-de-la-presbicia\/","title":{"rendered":"Estrategias de visi\u00f3n simult\u00e1nea para la correcci\u00f3n de la presbicia"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">_DSC1299.JPG<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/33817062-00F0-41A0-B953-3817D9E3CF8C\/Cuerpo\/_DSC1299.JPG\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>En esta sesi\u00f3n, los expertos han tratado sobre las bases f\u00edsicas y de adaptaci\u00f3n neural a la visi\u00f3n simult\u00e1nea. As\u00ed como del an\u00e1lisis individualizado de las indicaciones y de las ventajas e inconvenientes de las distintas soluciones seg\u00fan sean lentes de contacto, cirug\u00eda refractiva corneal o lentes intraoculares el medio corrector seleccionado. Arthur Bradley ha comenzado esta sesi\u00f3n descubriendo los principales aspecto de la visi\u00f3n simult\u00e1nea. <\/p>\n<p>Por su parte David Madrid Costa ha mostrado el estado actual sobre la compensaci\u00f3n de la presbicia con lentes de contacto, analizando los diferentes aspectos que permiten mejorar la adaptaci\u00f3n de las lentes de contacto multifocales. <\/p>\n<p>El Dr. Miguel \u00c1ngel Teus ha analizado la eficacia y seguridad que actualmente existe e la correcci\u00f3n de presbicia mediante cirug\u00eda corneal.<\/p>\n<p>Y finalmente, Nuria Garz\u00f3n ha dado a conocer c\u00f3mo funcionan las lentes intraoculares multifocales.<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/B8F8CD2B-877D-4038-99B4-9BF2F75D0309\/33817062-00F0-41A0-B953-3817D9E3CF8C\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En la sesi\u00f3n plenaria del s\u00e1bado de OPTOM 2018, los expertos han tratado sobre las bases f\u00edsicas y de adaptaci\u00f3n neural a la visi\u00f3n simult\u00e1nea. As\u00ed como del an\u00e1lisis individualizado de las indicaciones y de las ventajas e inconvenientes de las distintas soluciones seg\u00fan sean lentes de contacto, cirug\u00eda refractiva corneal o lentes intraoculares el medio corrector seleccionado.<\/p>\n","protected":false},"featured_media":1432,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":true,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[36],"tags":[],"class_list":["post-605","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-de-prensa"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/605","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1432"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=605"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=605"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=605"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}