<!---->{"id":607,"date":"2016-11-14T00:00:00","date_gmt":"2016-11-13T23:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/gran-exito-de-la-accion-solidaria-con-refugiados-auspiciada-por-la-fundacion-salud-visual-en-madrid\/"},"modified":"2023-01-18T01:19:21","modified_gmt":"2023-01-18T00:19:21","slug":"gran-exito-de-la-accion-solidaria-con-refugiados-auspiciada-por-la-fundacion-salud-visual-en-madrid","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/gran-exito-de-la-accion-solidaria-con-refugiados-auspiciada-por-la-fundacion-salud-visual-en-madrid\/","title":{"rendered":"Gran \u00e9xito de la acci\u00f3n solidaria con refugiados auspiciada por la Fundaci\u00f3n Salud Visual en Madrid"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">jornadascnoo.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/04CA5497-46B1-4855-B3D0-2F441FEAE411\/Cuerpo\/jornadascnoo.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\nLa Fundaci\u00f3n Salud Visual (FUNSAVI,) auspiciada por el Colegio Nacional de \u00d3pticos-Optometristas (CNOO), se acerc\u00f3 a las personas m\u00e1s vulnerables que viven en la Comunidad de Madrid aportando todos sus conocimientos cient\u00edfico-sanitarios y soluciones oft\u00e1lmicas. En esta ocasi\u00f3n, en el marco del programa \u201cFunsavi Social\u201d, un equipo de profesionales \u00f3pticos-optometristas se desplazaron de forma voluntaria desde varios puntos de la geograf\u00eda espa\u00f1ola para participar en esta importante iniciativa solidaria que, sin duda, ha sido muy importante para la salud visual de los refugiados recibidos en la Comunidad de Madrid. \u201cLa Fundaci\u00f3n Salud Visual (FUNSAVI) est\u00e1 profundamente comprometida con los m\u00e1s desfavorecidos y consideramos que desde&nbsp;nuestra posici\u00f3n, como profesionales de atenci\u00f3n primaria de salud visual, nos vemos en la obligaci\u00f3n de contribuir a crear una sociedad&nbsp;mejor y m\u00e1s saludable. Para los que trabajamos en la Fundaci\u00f3n, la solidaridad desde la atenci\u00f3n optom\u00e9trica cumple dos funciones&nbsp;muy positivas: aportar una buena visi\u00f3n a los integrantes de las familias m\u00e1s necesitadas, como por ejemplo los refugiados que viven en Espa\u00f1a, y por otro lado transmitir a la sociedad la importancia de los valores de solidaridad y generosidad\u201d, explic\u00f3 Luis Alfonso Garc\u00eda Guti\u00e9rrez, secretario general de FUNSAVI.<br \/>Los voluntarios que participaron en la jornada solidaria acudieron al hotel NH Collection Madrid Eurobuilding, sede de las Jornadas Cl\u00ednicas del CNOO y de la iniciativa social de la Fundaci\u00f3n con refugiados. El trabajo que realizaron, en un doble turno de ma\u00f1ana y tarde, conform\u00f3 un total de m\u00e1s de siete horas de revisiones optom\u00e9tricas. Funsavi puso a disposici\u00f3n de los refugiados las monturas y las lentes que fueron necesarias tras las revisiones visuales practicadas por los especialistas.<br \/>La Fundaci\u00f3n Salud Visual, en colaboraci\u00f3n con FDI, organiz\u00f3 dicha jornada invitando a colectivos vulnerables de diversos centros de la Confederaci\u00f3n Espa\u00f1ola de Atenci\u00f3n al Refugiado (CEAR), y la Asociaci\u00f3n de Apoyo al Pueblo Sirio (AAPS). La satisfacci\u00f3n por la atenci\u00f3n primaria de la salud visual, recibida por cada una de las personas refugiadas y atendidas por \u00f3pticos-optometristas, fue el mejor indicador de la importancia de esta acci\u00f3n solidaria cuyo objetivo ha sido ayudar a aquellos que han tenido que dejar sus pa\u00edses por encontrarse en conflicto, buscando junto con sus familias un estado de bienestar a trav\u00e9s de la integraci\u00f3n.<br \/>Con esta acci\u00f3n social, Funsavi pone en marcha un proyecto global de voluntariado bajo el programa #funsavisocial, en el que \u00f3pticos-optometristas podr\u00e1n participar en jornadas formativas de salud visual en colegios, ex\u00e1menes visuales de colectivos vulnerables y programas internacionales.<br \/>&nbsp;\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/04CA5497-46B1-4855-B3D0-2F441FEAE411\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de las Jornadas Cl\u00ednicas del Colegio Nacional de \u00d3pticos-Optometristas, que se desarrollaron el pasado fin de semana en el Hotel NH Collection Madrid Eurobuilding, con m\u00e1s de 350 participantes, la Fundaci\u00f3n Salud Visual (FUNSAVI) auspici\u00f3 una acci\u00f3n solidaria realizando ex\u00e1menes visuales a un gran n\u00famero de refugiados de la Comunidad de Madrid.<\/p>\n","protected":false},"featured_media":1550,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-607","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1550"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}