<!---->{"id":655,"date":"2018-09-10T00:00:00","date_gmt":"2018-09-09T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/ver-para-crecer-aporta-gafas-solidarias-para-una-segunda-oportunidad\/"},"modified":"2023-01-18T01:16:52","modified_gmt":"2023-01-18T00:16:52","slug":"ver-para-crecer-aporta-gafas-solidarias-para-una-segunda-oportunidad","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/ver-para-crecer-aporta-gafas-solidarias-para-una-segunda-oportunidad\/","title":{"rendered":"Ver para Crecer aporta gafas solidarias para una segunda oportunidad"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">verparacrecer.JPG<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/764EA3C8-B062-4CC1-9759-04C1EE412D2A\/Cuerpo\/verparacrecer.JPG\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>En aproximadamente un mes, las 74 personas que<br \/>\nnecesitaban gafas para sus problemas de visi\u00f3n<br \/>\nlas recibieron nuevas, con la montura que eligieron<br \/>\nentre una amplia selecci\u00f3n. Con ellas tendr\u00e1n<br \/>\nmejores opciones para formarse, aprender y, con<br \/>\nel apoyo de las instituciones que les tutelan, encontrar<br \/>\nun trabajo para salir de su situaci\u00f3n.\n<\/p>\n<p>Luisa es una de las personas sin hogar a las que la<br \/>\nAsociaci\u00f3n Bona Voluntat en Acci\u00f3 ayuda en su itinerario<br \/>\nde reinserci\u00f3n social. Lleva unas gafas con correcci\u00f3n<br \/>\nsolo para ver de lejos, pero tiene problemas en<br \/>\nvisi\u00f3n pr\u00f3xima. Los cambios de enfoque le provocan<br \/>\ndolor de cabeza, y as\u00ed es m\u00e1s dif\u00edcil aprender y encontrar<br \/>\nuna segunda oportunidad en la vida.\n<\/p>\n<p>Recientemente, los \u00f3pticos-optometristas de VpC, de cuyo<br \/>\ninicio se han cumplido en junio tres a\u00f1os, graduaron la visi\u00f3n<br \/>\nde Luisa en la que fue la vig\u00e9simo cuarta acci\u00f3n sobre el<br \/>\nterreno \u2014tercera en Barcelona\u2014 del proyecto en Espa\u00f1a.<br \/>\nEl proyecto Ver para Crecer se apoya en la experiencia<br \/>\nen materia de cooperaci\u00f3n internacional en el \u00e1mbito<br \/>\nde la Salud Visual de la Fundaci\u00f3n Cione Ruta de la&nbsp;<span style=\"font-family: Tahoma; font-size: 12px;\">Luz y en la capacidad tecnol\u00f3gica de la iniciativa Vision&nbsp;<\/span><span style=\"font-family: Tahoma; font-size: 12px;\">For Life, de Essilor. Su objetivo es revisar la visi\u00f3n de&nbsp;<\/span><span style=\"font-family: Tahoma; font-size: 12px;\">personas en situaci\u00f3n de vulnerabilidad, de manera que&nbsp;<\/span>quienes necesitan unas gafas porque su situaci\u00f3n coyuntural<br \/>\nno les permite coste\u00e1rselas, las reciben nuevas. Cada uno de los cien beneficiarios revisado ten\u00eda su propia historia, que las entidades que los acogen, Sant Joan de D\u00e9u-Serveis Socials\/Obra Social, la Fundaci\u00f3n Bayt Al-thaqafa, Centre d\u2019Acollida Ass\u00eds y Bona Voluntat en Acci\u00f3, les ayudan diariamente a cambiar.<\/p>\n<p>Por el perfil de beneficiarios\/as de las tres instituciones<br \/>\nque colaboraron con el proyecto, las revisiones visuales<br \/>\nson muy necesarias. En Sant Joan de D\u00e9u todos los casos<br \/>\nson de personas sin hogar y en riesgo de exclusi\u00f3n<br \/>\nsocial, mayores de 18 a\u00f1os. \u201cPara los residentes que<br \/>\npresentan limitaciones a nivel visual, y aunque el sistema<br \/>\nde protecci\u00f3n p\u00fablico garantiza atenci\u00f3n y seguimiento<br \/>\ntanto en atenci\u00f3n primaria como en especializada, no<br \/>\nexiste una cobertura expresa para paliar el coste que<br \/>\npuede representar la obtenci\u00f3n de un elemento correctivo,<br \/>\ntan necesario e imprescindible, como pueden ser<br \/>\nunas gafas. En la mayor\u00eda de los casos, las entidades<br \/>\nsociales establecemos alianzas con centros sanitarios<br \/>\nde \u00f3ptica, colegios profesionales, etc\u00e9tera, para garantizar<br \/>\nque, independientemente de la ausencia de ingresos econ\u00f3micos, la persona tenga acceso a la soluci\u00f3n correctiva<br \/>\nque necesite. Buen ejemplo de ello son estas acciones<br \/>\nde Ver Para Crecer\u201d termina Sillero. Sant Joan de<br \/>\nD\u00e9u Serveis Socials Barcelona ofrece una atenci\u00f3n integral<br \/>\na sus beneficiarios, atenci\u00f3n sicol\u00f3gica, f\u00edsica, social<br \/>\ny tambi\u00e9n espiritual. Desde diferentes \u00e1mbitos, trata de<br \/>\nmejorar su situaci\u00f3n para que puedan optar a una vivienda<br \/>\ny en muchos casos tambi\u00e9n a un puesto de trabajo.<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/0C1E2A82-D862-457D-B487-76344D5D5E62\/764EA3C8-B062-4CC1-9759-04C1EE412D2A\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El proyecto Ver para Crecer (VpC) que cumple sus primeros tres a\u00f1os de misiones \u00f3pticas en Espa\u00f1a, revis\u00f3 recientemente la vista de cien beneficiarios\/as en riesgo de exclusi\u00f3n social en colaboraci\u00f3n con Sant Joan de Deu-Serveis Socials-Obra Social.<\/p>\n","protected":false},"featured_media":1482,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[45],"tags":[],"class_list":["post-655","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-funsavi-social"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1482"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=655"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=655"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}