<!---->{"id":715,"date":"2015-06-15T11:07:00","date_gmt":"2015-06-15T09:07:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/consumo-excesivo-de-alcohol-podria-causar-danos-en-la-vision\/"},"modified":"2023-01-18T01:19:05","modified_gmt":"2023-01-18T00:19:05","slug":"consumo-excesivo-de-alcohol-podria-causar-danos-en-la-vision","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/consumo-excesivo-de-alcohol-podria-causar-danos-en-la-vision\/","title":{"rendered":"Consumo excesivo de alcohol podr\u00eda causar da\u00f1os en la visi\u00f3n"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">355&#215;263-001.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/841AAFB1-9EDE-46B9-AA75-29488B9084D2\/Cuerpo\/355x263-001.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>&ldquo;La afectaci&oacute;n que causa el alcoholismo en la retina no est&aacute; descrita a d&iacute;a de hoy pero las evidencias cient&iacute;ficas se acumulan. El equipo de investigadores de la UCV dirigido por el doctor Francisco Javier Romero, con el que he llevado a cabo la tesis, ya hab&iacute;a demostrado en animales lo que expongo en este estudio, pero ahora ya ha quedado probado en un tejido humano&rdquo;, ha argumentado. Ahora bien, el experto ha puntualizado que estas investigaciones van a continuar con el objetivo de caracterizar la mencionada afectaci&oacute;n de la retina de muchas m&aacute;s maneras y, as&iacute;, a que esta pase a formar parte de la literatura cient&iacute;fica. <br \/>Para llevar a cabo el trabajo, Flores ha partido en su estudio de la descripci&oacute;n del epitelio pigmentario de la retina, uno de los tejidos que forman parte de la capa que la envuelve. Este se encuentra en una &ldquo;estrecha&rdquo; relaci&oacute;n con los fotorreceptores, las c&eacute;lulas de la retina capaces de absorber los fotones &ldquo;que permiten transformar la energ&iacute;a de la luz en informaci&oacute;n visual en el cerebro&rdquo;. De ese modo, cualquier da&ntilde;o que pueda producirse en el epitelio afectar&aacute; a los fotorreceptores y, por tanto, a la capacidad visual. <br \/>&ldquo;Existen muchos estudios sobre el epitelio pigmentario, a causa de enfermedades como la degeneraci&oacute;n macular asociada a la edad o la retinopat&iacute;a diab&eacute;tica que producen da&ntilde;o en este y, como consecuencia, conducen a la ceguera. Elegimos para esta investigaci&oacute;n el epitelio pigmentario, adem&aacute;s de por su estrecha relaci&oacute;n con los fotorreceptores, porque existe una uni&oacute;n directa con la coroides, la capa del ojo que le aporta la sangre. En este tejido se produce un transporte muy intenso de los nutrientes que est&aacute;n en la sangre, incluido el etanol, si se trata de un sujeto alcoh&oacute;lico&rdquo;, ha se&ntilde;alado.<\/p>\n<p>En concreto, Flores ha encontrado las tres enzimas principales para metabolizar el alcohol en este tejido (catalasa, la alcohol deshidrogenasa y el citocromo), y ha caracterizado el da&ntilde;o producido en la retina.&ldquo;Un alto nivel de etanol en sangre produce que este llegue al tejido del epitelio pigmentario, al que va produci&eacute;ndole progresivamente un da&ntilde;o. Los fotorreceptores se ven tambi&eacute;n afectados y, finalmente esto causa problemas a la visi&oacute;n&rdquo;, concluy&oacute;.<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/841AAFB1-9EDE-46B9-AA75-29488B9084D2\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El consumo excesivo de alcohol podr\u00eda causar da\u00f1os en la visi\u00f3n debido a que la retina es capaz de metabolizarlo, seg\u00fan ha mostrado una investigaci\u00f3n realizada por un equipo multidisciplinar de cient\u00edficos, dirigido por Miguel Flores, de la Universidad Cat\u00f3lica de Valencia.<\/p>\n","protected":false},"featured_media":1542,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-715","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1542"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}