<!---->{"id":744,"date":"2018-01-08T00:00:00","date_gmt":"2018-01-07T23:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/cientificos-avanzan-para-llevar-a-la-clinica-el-uso-de-celulas-madre-para-enfermedades-oculares\/"},"modified":"2023-01-18T01:20:08","modified_gmt":"2023-01-18T00:20:08","slug":"cientificos-avanzan-para-llevar-a-la-clinica-el-uso-de-celulas-madre-para-enfermedades-oculares","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/cientificos-avanzan-para-llevar-a-la-clinica-el-uso-de-celulas-madre-para-enfermedades-oculares\/","title":{"rendered":"Cient\u00edficos avanzan para llevar a la cl\u00ednica el uso de c\u00e9lulas madre para enfermedades oculares"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">stem-cell-163711_128.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/C46CD7D3-BAEA-4A62-8EE4-3FD9A0A7B4A5\/Cuerpo\/stem-cell-163711_128.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>Cient\u00edficos del Instituto Nacional del Ojo (NEI, por sus siglas en ingl\u00e9s), que forma parte de los Institutos Nacionales de Salud estadounidenses, informan que peque\u00f1as protuberancias en forma de tubo llamadas cilios primarios en las c\u00e9lulas del epitelio pigmentario de la retina (EPR) &#8211;una capa de c\u00e9lulas en la parte posterior del ojo&#8211; son esenciales para la supervivencia de los fotorreceptores sensibles a la luz de la retina.<\/p>\n<p>&quot;Ahora tenemos una mejor idea sobre c\u00f3mo generar y reemplazar c\u00e9lulas del EPR, que parecen estar entre las primeras en dejar de funcionar correctamente en la DMAE&quot;, subraya el investigador principal del estudio, Kapil Bharti, investigador en NEI. Bharti lidera el desarrollo de EPR derivado de c\u00e9lulas madre del paciente para un ensayo cl\u00ednico de DMAE que se lanzar\u00e1 en 2018.<\/p>\n<p>En un ojo sano, las c\u00e9lulas del EPR nutren y soportan los fotorreceptores, las c\u00e9lulas que convierten la luz en se\u00f1ales el\u00e9ctricas que viajan al cerebro a trav\u00e9s del nervio \u00f3ptico. Las c\u00e9lulas EPR forman una capa justo detr\u00e1s de los fotorreceptores. En la atrofia geogr\u00e1fica, las c\u00e9lulas del EPR mueren, lo que hace que los fotorreceptores se degeneren, causando la p\u00e9rdida de la visi\u00f3n.<\/p>\n<p>Bharti y sus colegas, cuyo trabajo se detalla este martes en &#39;Cell Reports&#39;, esperan detener e invertir la progresi\u00f3n de la atrofia geogr\u00e1fica mediante la sustituci\u00f3n del ERP enfermo por un ERP hecho en el laboratorio. El enfoque implica el uso de las c\u00e9lulas sangu\u00edneas de un paciente para generar c\u00e9lulas madre pluripotentes inducidas (iPSCs, por sus siglas en ingl\u00e9s), c\u00e9lulas capaces de convertirse en cualquier tipo de c\u00e9lula en el cuerpo. Las iPSCs se cultivan en el laboratorio y luego se les persuade para que se conviertan en EPR para la implantaci\u00f3n quir\u00fargica.<\/p>\n<p>No obstante, los intentos de crear implantes EPR funcionales se han topado con un obst\u00e1culo recurrente: las iPSCs programadas para convertirse en c\u00e9lulas del EPR tienen una tendencia a atascarse en el desarrollo, dice Bharti. &quot;Las c\u00e9lulas con frecuencia no maduran en un EPR funcional capaz de soportar fotorreceptores. Sin embargo, en los casos en que maduran, la maduraci\u00f3n del ERP coincide con la aparici\u00f3n de cilios primarios en las c\u00e9lulas iPSC- EPR&quot;.<\/p>\n<p><strong>FUNCIONES SIMILARES A LAS DEL EPITELIO PIGMENTARIO DE LA RETINA<\/strong><\/p>\n<p>Los investigadores probaron tres f\u00e1rmacos conocidos por modular el crecimiento de los cilios primarios en el EPR derivado de iPSC. Como se predijo, los dos medicamentos conocidos por impulsar el crecimiento de los cilios mejoraron significativamente la maduraci\u00f3n estructural y funcional del EPR derivado de iPSC. Una caracter\u00edstica importante de la madurez observada fue que todas las c\u00e9lulas del ERP se orientaron adecuadamente, formando correctamente una sola monocapa funcional.<\/p>\n<p>El perfil de expresi\u00f3n del gen de las c\u00e9lulas EPR derivadas de iPSC tambi\u00e9n se parec\u00eda al de las c\u00e9lulas del EPR adulto. Y, lo que es m\u00e1s importante, las c\u00e9lulas desempe\u00f1aban una funci\u00f3n crucial de las c\u00e9lulas EPR maduras: engull\u00edan las puntas de los segmentos externos de los fotorreceptores, un proceso de poda que mantiene a los fotorreceptores funcionando correctamente.<\/p>\n<p>Por el contrario, las c\u00e9lulas EPR derivadas de iPSC expuestas al tercer f\u00e1rmaco, un inhibidor del crecimiento de los cilios, demostraron una estructura y funcionalidad severamente alteradas. Como confirmaci\u00f3n adicional de sus observaciones, cuando los autores destruyeron gen\u00e9ticamente la expresi\u00f3n de la prote\u00edna ciliar IFT88, el EPR derivado de iPSC mostr\u00f3 maduraci\u00f3n severa y defectos funcionales, seg\u00fan lo confirmado por el an\u00e1lisis de expresi\u00f3n g\u00e9nica.<\/p>\n<p>La tinci\u00f3n tisular mostr\u00f3 que la eliminaci\u00f3n de IFT88 conduc\u00eda a una menor densidad de c\u00e9lulas EPR derivadas de iPSC y polaridad funcional, es decir, las c\u00e9lulas dentro del tejido de EPR apuntaban en la direcci\u00f3n incorrecta. Bharti y su grupo encontraron resultados similares en c\u00e9lulas pulmonares derivadas de iPSC, otro tipo de c\u00e9lula epitelial con cilios primarios. Cuando las c\u00e9lulas de pulm\u00f3n derivadas de iPSC se expusieron a f\u00e1rmacos que potencian el crecimiento de los cilios, la inmunotinci\u00f3n confirm\u00f3 que las c\u00e9lulas se ve\u00edan estructuralmente maduras.<\/p>\n<p>El informe sugiere que los cilios primarios regulan la supresi\u00f3n de la v\u00eda can\u00f3nica WNT, una v\u00eda de se\u00f1alizaci\u00f3n celular implicada en el desarrollo embrionario. La supresi\u00f3n de la v\u00eda WNT durante el desarrollo de EPR instruye a las c\u00e9lulas para que dejen de dividirse y comiencen a diferenciarse en EPR adulto, seg\u00fan los investigadores.<\/p>\n<p>Los cient\u00edficos tambi\u00e9n generaron EPR derivado de iPSC de un paciente con ciliopat\u00eda, un trastorno que causa la p\u00e9rdida severa de la visi\u00f3n debido a la degeneraci\u00f3n de los fotorreceptores. La ciliopat\u00eda del paciente se asoci\u00f3 con mutaciones del gen de cilios CEP290. Comparado con un donante sano, el EPR derivado de iPSC del paciente con ciliopat\u00eda ten\u00eda cilios que eran m\u00e1s peque\u00f1os. El EPR derivado del iPSC del paciente tambi\u00e9n presentaba maduraci\u00f3n y defectos funcionales similares a los que presentaban el declive de IFT88.<\/p>\n<p>Nuevos estudios en un modelo de rat\u00f3n de ciliopat\u00eda confirmaron una importante relaci\u00f3n temporal: mirando a trav\u00e9s de varias etapas de desarrollo temprano, los defectos del EPR precedieron a la degeneraci\u00f3n del fotorreceptor, que proporciona informaci\u00f3n adicional sobre la degeneraci\u00f3n retiniana inducida por ciliopat\u00eda.<\/p>\n<p>Los hallazgos del estudio se han incorporado al protocolo del grupo para producir EPR de grado cl\u00ednico derivado de iPSC. Tambi\u00e9n aportar\u00e1n informaci\u00f3n sobre el desarrollo de modelos de enfermedades para la investigaci\u00f3n de la DMAE y otras enfermedades retinianas degenerativas, concluye Bharti.<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/C46CD7D3-BAEA-4A62-8EE4-3FD9A0A7B4A5\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El descubrimiento da un paso m\u00e1s en los esfuerzos para producir EPR derivado de c\u00e9lulas madre para trasplante en pacientes con atrofia geogr\u00e1fica, tambi\u00e9n conocida como degeneraci\u00f3n macular relacionada con la edad (DMAE) de tipo seca, una de las principales causas de ceguera en Estados Unidos.<\/p>\n","protected":false},"featured_media":1571,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-744","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/744","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1571"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=744"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=744"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=744"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}