<!---->{"id":748,"date":"2017-07-17T00:00:00","date_gmt":"2017-07-16T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/cgcoo-seo-y-funsavi-firman-un-convenio-de-colaboracion-con-semergen\/"},"modified":"2023-01-18T01:20:44","modified_gmt":"2023-01-18T00:20:44","slug":"cgcoo-seo-y-funsavi-firman-un-convenio-de-colaboracion-con-semergen","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/cgcoo-seo-y-funsavi-firman-un-convenio-de-colaboracion-con-semergen\/","title":{"rendered":"CGCOO, SEO y Funsavi firman un convenio de colaboraci\u00f3n con SEMERGEN"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">01.Firmadelacuerdo.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/E175EBB4-A544-4A19-A210-4362C6D026B1\/Cuerpo\/01.Firmadelacuerdo.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\nParticiparon en dicho acto oficial el presidente de SEMERGEN, Jos\u00e9 Luis Llisterri Caro, el presidente del CGCOO, Juan Carlos Mart\u00ednez Moral, la vicepresidenta de la SEO, Clara Penelas \u00c9cija y el secretario de FUNSAVI, Luis Alfonso Garc\u00eda Guti\u00e9rrez.<br \/>El Convenio Marco establece el entorno de referencia para la acci\u00f3n coordinada entre SEMERGEN, CGCOO, SEO y FUNSAVI, tanto sobre el intercambio de informaci\u00f3n que pueda ser de inter\u00e9s a los fines de ambas asociaciones, como en el desarrollo de aquellas actuaciones encaminadas a potenciar la formaci\u00f3n de los profesionales de todas estas instituciones, el desarrollo de actividades de investigaci\u00f3n, as\u00ed como la celebraci\u00f3n de seminarios, cursos y conferencias sobre temas de inter\u00e9s com\u00fan. <br \/>No obstante, la estrecha colaboraci\u00f3n de la Organizaci\u00f3n Colegial \u00d3ptico-Optom\u00e9trica con SEMERGEN se inici\u00f3 hace unos meses con la firma de un primer Convenio Marco y el Documento de Consenso \u201cEl \u00f3ptico-optometrista en el control de la diabetes\u201d para la puesta en marcha, en colaboraci\u00f3n con la Federaci\u00f3n Espa\u00f1ola de Diabetes (FEDE), de la campa\u00f1a \u201cMira por tu Diabetes\u201d cuyo objetivo principal fue promover la mejor atenci\u00f3n visual a los pacientes con esta patolog\u00eda sist\u00e9mica en los establecimientos sanitarios de \u00f3ptica. <br \/>Esta iniciativa, que se retomar\u00e1 nuevamente este mismo a\u00f1o, pretende animar a los pacientes diab\u00e9ticos a realizarse ex\u00e1menes visuales peri\u00f3dicamente en los establecimientos sanitarios de \u00f3ptica. <br \/>Entre otras actividades, el convenio permitir\u00e1 y fomentar\u00e1 la colaboraci\u00f3n activa de \u00f3pticos-optometristas y m\u00e9dicos de atenci\u00f3n primaria en los congresos internacionales organizados tanto por el CGCOO (OPTOM) como por SEMERGEN. Mesas redondas y talleres en donde se debatir\u00e1 sobre la necesidad e importancia de la figura del \u00f3ptico-optometrista en la detecci\u00f3n de patolog\u00edas oculares de origen sist\u00e9mico y su incorporaci\u00f3n paulatina en distintos departamentos de la sanidad p\u00fablica espa\u00f1ola.<br \/>Seg\u00fan palabras de Juan Carlos Mart\u00ednez Moral tras la firma del convenio marco \u201cEstamos plenamente convencidos que dicha colaboraci\u00f3n beneficiar\u00e1 no solo a las instituciones firmantes sino tambi\u00e9n a los pacientes que atendemos y al sistema sanitario espa\u00f1ol, sin detrimento del ejercicio de las actividades que, en la actualidad o en el futuro, podamos llevar a cabo por separado en el ejercicio de nuestras respectivas competencias\u201d.<br \/>Por su parte, Jos\u00e9 Luis Llisterri Caro subray\u00f3 la importancia de la firma de convenios como este. \u201cLa atenci\u00f3n primaria sanitaria multidisciplinar es hoy m\u00e1s importante que nunca, la firma de estos convenio marco ofrece una manera de organizar y abarcar el conjunto de la atenci\u00f3n de la salud desde distintos frentes, desde los hogares, pasando por los centros de salud, los establecimientos sanitarios de \u00f3ptica (en el caso de disfunciones visuales) hasta los hospitales, en la que la prevenci\u00f3n es tan importante como la cura, y en la que se deben invertir recursos de forma racional en los distintos niveles de atenci\u00f3n, empezando por la inclusi\u00f3n de profesionales adecuados en cada \u00e1rea sanitaria\u201d.<br \/>Por \u00faltimo, y previo acuerdo entre las partes, en el convenio marco suscrito se acepta la inclusi\u00f3n y colaboraci\u00f3n con otras instituciones, fundaciones, sociedades cient\u00edficas y centros de investigaci\u00f3n, tanto de car\u00e1cter nacional o internacional y tanto gubernamentales como p\u00fablicas o privadas, siempre con el objetivo puesto en una mejor y m\u00e1s personalizada atenci\u00f3n sanitaria a la sociedad. <br \/>&nbsp;\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/E175EBB4-A544-4A19-A210-4362C6D026B1\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 10 de julio, en la sede de la Organizaci\u00f3n Colegial \u00d3ptico-Optom\u00e9trica en Madrid, se firm\u00f3 el Convenio Marco de colaboraci\u00f3n entre la Sociedad Espa\u00f1ola de M\u00e9dicos de Atenci\u00f3n Primaria (SEMERGEN), el Consejo General de Colegios de \u00d3pticos-Optometristas (CGCOO), la Sociedad Espa\u00f1ola de Optometr\u00eda (SEO) y la Fundaci\u00f3n Salud Visual (FUNSAVI).<\/p>\n","protected":false},"featured_media":1574,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-748","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1574"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}