<!---->{"id":796,"date":"2013-04-16T10:00:00","date_gmt":"2013-04-16T08:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/presentacion-a-los-medios-de-la-semana-de-la-salud-visual\/"},"modified":"2023-01-18T01:23:05","modified_gmt":"2023-01-18T00:23:05","slug":"presentacion-a-los-medios-de-la-semana-de-la-salud-visual","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/presentacion-a-los-medios-de-la-semana-de-la-salud-visual\/","title":{"rendered":"Presentaci\u00f3n a los medios de la Semana de la Salud Visual"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">1.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/06782946-5493-4DE1-AAE2-5ABA65D66CE8\/Cuerpo\/1.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>El pasado 11 de diciembre, el sal\u00f3n de actos del Consejo General de Colegios de \u00d3pticos-Optometristas acogi\u00f3 el acto de presentaci\u00f3n a los medios de la Semana de la Salud Visual 2012. La campa\u00f1a, la primera iniciativa puesta en marcha por la Fundaci\u00f3n Visual, Desarrollo Optom\u00e9trico y Audiol\u00f3gico, en colaboraci\u00f3n con la Sociedad Espa\u00f1ola de Geriatr\u00eda y Gerontolog\u00eda, se celebr\u00f3 entre los d\u00edas 10 y 16 de diciembre bajo el lema <b>\u201cCuida tus ojos. Evita MAYORES problemas\u201d<\/b>. El tema escogido para esta edici\u00f3n fue la atenci\u00f3n visual a las personas que superan los 50 a\u00f1os.<\/p>\n<p>Tras agradecer la presencia a los asistentes, Juan Carlos Mart\u00ednez Moral, presidente de la Fundaci\u00f3n Visual, aprovech\u00f3 para presentar oficialmente la nueva entidad ante los medios de comunicaci\u00f3n, sin olvidarse de pormenorizar los detalles de la campa\u00f1a. As\u00ed, Mart\u00ednez Moral hizo un repaso de las cuatro patolog\u00edas responsables de la mayor\u00eda de casos de p\u00e9rdida de la visi\u00f3n (cataratas, DMAE, glaucoma y retinopat\u00eda diab\u00e9tica) para recalcar que \u201cla prevenci\u00f3n en estadios primarios garantiza una mayor calidad de vida\u201d. \u201cLa prevenci\u00f3n puede parecer cara ahora, pero resulta muy barata en el futuro\u201d, afirm\u00f3.<\/p>\n<p>A continuaci\u00f3n, el Dr. Primitivo Ramos, presidente de la Sociedad Madrile\u00f1a de Geriatr\u00eda y Gerontolog\u00eda, destac\u00f3 la incidencia \u201calarmante\u201d de los defectos de visi\u00f3n en ese segmento de edad, a los que se suelen unir los problemas de audici\u00f3n. \u201cLa persona mayor no es consciente de ellos y sobreestima sus capacidades visuales\u201d, se\u00f1al\u00f3, destacando, sin embargo, que \u201csolo el 20% ve bien\u201d. En su opini\u00f3n, los problemas visuales pueden tener repercusiones negativas en el estado f\u00edsico, aumentando el riesgo de ca\u00eddas o fracturas, adem\u00e1s de en la esfera relacional, afectiva y social, favoreciendo \u201cla soledad y el aislamiento\u201d.<\/p>\n<p>Finalmente, Luis Alfonso Garc\u00eda, secretario general de la Fundaci\u00f3n Salud Visual, tom\u00f3 la palabra para destacar que \u201cla p\u00e9rdida de visi\u00f3n no es una consecuencia normal del envejecimiento\u201d y que una simple visita anual al \u00f3ptico-optometrista contribuye a evitar la mayor\u00eda de los problemas. \u201cEl \u00f3ptico-optometrista proporciona al sistema nacional de salud un apoyo log\u00edstico cercano y de f\u00e1cil acceso\u201d, se\u00f1al\u00f3.<\/p>\n<p>La Semana de la Salud Visual 2012 se celebr\u00f3 en m\u00e1s de 5.000 establecimientos sanitarios de \u00f3ptica, as\u00ed como centros y consultorios de salud, 2.000 centros residenciales y de d\u00eda y servicios de geriatr\u00eda hospitalaria. La campa\u00f1a contempl\u00f3 el reparto de 250.000 folletos informativos y 10.000 carteles dirigidos a la poblaci\u00f3n general con las recomendaciones b\u00e1sicas para detectar posibles problemas y cuidar la salud visual.<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/06782946-5493-4DE1-AAE2-5ABA65D66CE8\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La campa\u00f1a, una iniciativa puesta en marcha por la Fundaci\u00f3n Salud Visual en colaboraci\u00f3n con<br \/>\nla Sociedad Espa\u00f1ola de Geriatr\u00eda y Gerontolog\u00eda, se desarroll\u00f3 entre los d\u00edas 10 y 16 de diciembre.<\/p>\n","protected":false},"featured_media":1622,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-796","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1622"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=796"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=796"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}