<!---->{"id":824,"date":"2014-08-27T00:00:00","date_gmt":"2014-08-26T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/tus-ojos-en-plena-forma-para-hacer-deporte\/"},"modified":"2023-01-18T01:24:04","modified_gmt":"2023-01-18T00:24:04","slug":"tus-ojos-en-plena-forma-para-hacer-deporte","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/tus-ojos-en-plena-forma-para-hacer-deporte\/","title":{"rendered":"Tus ojos en plena forma para hacer deporte"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">apoyog.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/C180E237-C30D-4285-AC63-6931F6A7B592\/Cuerpo\/apoyog.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<!-- Generated by XStandard version 2.0.5.0 on 2015-12-11T09:00:50 --><\/p>\n<p>M\u00e1s del ochenta por ciento de lo que percibimos proviene de la visi\u00f3n, dato que nos permite hacernos una idea del importante papel que desempe\u00f1an nuestros ojos en el terreno de juego. <br \/>Aunque la mayor\u00eda de los deportes se basan en el movimiento, la visi\u00f3n resulta imprescindible para dirigir y coordinar las distintas partes del cuerpo, al tiempo que nos permite captar, interpretar y anticipar el desplazamiento de otras personas y objetos. De hecho, una de las claves en el desempe\u00f1o deportivo es el procesamiento de la informaci\u00f3n visual, que nuestro cerebro debe interpretar de forma r\u00e1pida y precisa para realizar predicciones acertadas sobre lo que va a pasar en los pr\u00f3ximos segundos, normalmente bajo presi\u00f3n y en el intervalo m\u00e1s corto posible. <br \/>Las actividades f\u00edsicas que se desarrollan en ambientes muy cambiantes, como en la mayor\u00eda de los deportes de equipo, exigen una alta eficacia visual, de tal modo que el jugador pueda percibir el m\u00e1ximo de elementos en su campo de visi\u00f3n, procesarlos con rapidez y responder con la destreza necesaria. En definitiva, se trata de predecir el futuro bas\u00e1ndose en la percepci\u00f3n visual. <br \/>En el caso de los deportistas, as\u00ed como el ejercicio y el entrenamiento potencian aspectos como la velocidad y la fuerza, tambi\u00e9n pueden mejorar el de\u00adsempe\u00f1o ocular. Y, en consecuencia, cuanto m\u00e1s automatizadas est\u00e9n nuestras respuestas, mejor podremos captar, procesar y retener la informaci\u00f3n visual.<\/p>\n<h4 class=\"TituloWeb\"><strong>Una buena agudeza visual no es suficiente<\/strong><\/h4>\n<p>La agudeza visual, es decir, la habilidad para percibir correctamente los peque\u00f1os detalles de un objeto, resulta muy importante en los deportes, especialmente en aquellos que requieren distinguir elementos a grandes distancias, como el tiro. <br \/>Sin embargo, una buena agudeza visual \u00fanicamente se traduce en que podemos ver un objeto con claridad, pero no tiene en cuenta si conseguimos situarlo en el espacio, percibir la rapidez con que se desplaza o anticiparnos a un cambio en su trayectoria.<br \/>La agudeza constituye, por lo tanto, solo un aspecto m\u00e1s de nuestras capacidades visuales. La visi\u00f3n, de hecho, se puede describir como un sistema de procesamiento de informaci\u00f3n din\u00e1mico e interactivo, desarrollado a partir de nuestra experiencia, que nos permite comprender lo que vemos, movernos de manera eficiente en el espacio e interactuar con cualquier objeto.<br \/>Al practicar deporte, adem\u00e1s de la agudeza visual, entran en juego destrezas tan diversas como la coordinaci\u00f3n ojo-mano, el tiempo de reacci\u00f3n, la percepci\u00f3n perif\u00e9rica, la fijaci\u00f3n ocular, el enfoque y las habilidades de seguimiento. En el pasado, se supon\u00eda que, aparte de la correcci\u00f3n \u00f3ptica, poco m\u00e1s se pod\u00eda hacer para potenciar las capacidades visuales de un atleta. Hoy en d\u00eda, los deportistas de \u00e9lite pueden beneficiarse de una serie de ejercicios de entrenamiento visual dise\u00f1ados por un \u00d3ptico-Optometrista para alcanzar su m\u00e1ximo potencial en el terreno de juego.<\/p>\n<h4 class=\"TituloWeb\"><strong>Las habilidades de los campeones<\/strong><\/h4>\n<ul>\n<li><strong>Agudeza visual din\u00e1mica.<\/strong> Esta destreza permite discriminar objetos en movimiento, como una pelota de tenis o un bal\u00f3n de f\u00fatbol.<\/li>\n<li><strong>Concentraci\u00f3n visual.<\/strong> Los ojos normalmente reaccionan ante cualquier acontecimiento que se desarrolla en nuestro campo de visi\u00f3n, en ocasiones distray\u00e9ndonos de nuestro verdadero objetivo. Esta habilidad nos ayuda a centrarnos en el bal\u00f3n o el contrincante, ignorando el resto de elementos.<\/li>\n<li><strong>Coordinaci\u00f3n ojo-mano-cuerpo.<\/strong> La coordinaci\u00f3n ojo-mano-cuerpo se puede definir como el modo en que las manos, los pies y otros m\u00fasculos responden a la informaci\u00f3n percibida por los ojos de una manera r\u00e1pida y precisa.<\/li>\n<li><strong>Fijaci\u00f3n ocular.<\/strong> Cuando el bal\u00f3n o un oponente se mueve a gran velocidad, resulta fundamental ser capaz de seguirlo con el m\u00ednimo desplazamiento de la cabeza.<\/li>\n<li><strong>Memoria visual.<\/strong> Se trata de la habilidad para procesar y recordar una escena compleja con todos sus elementos en movimiento. Gracias a ella, los jugadores siempre parecen estar en el lugar adecuado en el momento preciso. Utilizando t\u00e9cnicas de escaneo, los investigadores han descubierto que las mismas \u00e1reas del cerebro que se activan al hacer deporte tambi\u00e9n reaccionan al visualizarnos practic\u00e1ndolo.<\/li>\n<li><strong>Percepci\u00f3n de la profundidad.<\/strong> Esta capacidad nos ayuda a juzgar con precisi\u00f3n la distancia y velocidad de los objetos u oponentes.<\/li>\n<li><strong>Visi\u00f3n perif\u00e9rica.<\/strong> Dado que muchas acciones no se desarrollan justo delante del jugador, la percepci\u00f3n de los elementos que se encuentran en los l\u00edmites del campo visual, sin necesidad de girar el cuello, proporciona una ventaja competitiva. Flexibilidad de enfoque Habilidad para cambiar el enfoque de forma r\u00e1pida de una distancia a otra.<\/li>\n<li><strong>Sensibilidad de contraste.<\/strong> Capacidad del sistema visual para distinguir entre un objeto y el fondo en el que se encuentra.<\/li>\n<li><strong>Visi\u00f3n del color. <\/strong>Distinguir claramente los diferentes colores y tonos es importante en los deportes de bal\u00f3n, como el f\u00fatbol.<\/li>\n<\/ul>\n<h4 class=\"TituloWeb\"><strong>Gafas que mejoran tu desempe\u00f1o<\/strong><\/h4>\n<p>Los atletas de todos los niveles pueden beneficiarse de gafas especialmente dise\u00f1adas para la actividad f\u00edsica. Por ejemplo, los tintes de algunas lentes filtran los reflejos y los colores de forma selectiva, haciendo que los objetos de un determinado tono se perciban claramente contrastados.<\/p>\n<h4 class=\"TituloWeb\"><strong>\u00a1No te olvides de la protecci\u00f3n!<\/strong><\/h4>\n<p>Todos los a\u00f1os, muchos ni\u00f1os y adultos sufren lesiones oculares al hacer deporte, y no solo en las actividades consideradas de riesgo. La buena noticia es que la mayor\u00eda de ellas se pueden prevenir utilizando la protecci\u00f3n adecuada. De hecho, los equipamientos han evolucionado tanto que las protecciones oculares casi se fabrican de manera espec\u00edfica para cada disciplina deportiva.<br \/>Por otra parte, no hay que olvidar que, cuando se est\u00e1 al aire libre, las gafas de sol ofrecen el mejor escudo frente a los efectos da\u00f1inos de la radiaci\u00f3n ultravioleta.<\/p>\n<div class=\"divDestacado\">\n<h4 class=\"TituloWeb\"><strong>Lentes de contacto, la opci\u00f3n ideal en el terreno de juego<\/strong><\/h4>\n<p>Las lentes de contacto ofrecen una gran comodidad al practicar deporte, por lo que, incluso si no deseas utilizarlas a diario, puedes optar por las de\u00adsechables y llevarlas solo en la pista de juego. Entre sus ventajas, destacan:<\/p>\n<ul>\n<li>Mejor visi\u00f3n perif\u00e9rica.<\/li>\n<li>Un campo visual absolutamente despejado.<\/li>\n<li>Menos probabilidades de empa\u00f1arse o ensuciarse.<\/li>\n<li>Visi\u00f3n m\u00e1s estable.<\/li>\n<li>Menor riesgo de lesiones.<\/li>\n<li>Mayor comodidad al utilizar equipos de protecci\u00f3n.<\/li>\n<\/ul>\n<p>Adem\u00e1s, pregunta a tu \u00f3ptico-optometrista acerca de la ortoqueratolog\u00eda o terapia refractiva corneal, un procedimiento que, mediante unas lentes de contacto especiales que se llevan solo mientras duermes, te permite ver correctamente sin necesidad de utilizar gafas.<\/p>\n<\/div>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/7AFC6C75-7167-4168-8813-4171C0ADB805\/C180E237-C30D-4285-AC63-6931F6A7B592\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La actividad f\u00edsica no es solo una cuesti\u00f3n de m\u00fasculos.<\/p>\n","protected":false},"featured_media":1650,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[68],"tags":[],"class_list":["post-824","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-salud-visual"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1650"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}