<!---->{"id":836,"date":"2015-10-20T00:00:00","date_gmt":"2015-10-19T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/proteccion-en-la-montana\/"},"modified":"2023-01-18T01:25:02","modified_gmt":"2023-01-18T00:25:02","slug":"proteccion-en-la-montana","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/proteccion-en-la-montana\/","title":{"rendered":"Protecci\u00f3n en la monta\u00f1a"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">gafsa.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/90651755-D77B-4761-A118-6DCD0A27785A\/Cuerpo\/gafsa.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<!-- Generated by XStandard version 2.0.5.0 on 2015-12-11T08:56:34 --><\/p>\n<p>Damos por hecho que para esquiar, deslizarnos con la tabla de snowboard o para hacer esqu\u00ed de traves\u00eda siempre vamos a ponernos un m\u00e1scara que proteja a ojos del viento, las part\u00edculas de la nieve y de la radiaci\u00f3n de sol, pero \u00bfsomos igual de conscientes que tambi\u00e9n debemos protegerlos cuando practicamos alpinismo, senderismo o simplemente pasamos una ma\u00f1ana en la monta\u00f1a?<\/p>\n<h4 class=\"TituloWeb\"><strong>Ojo con la altitud<\/strong><\/h4>\n<p>Bajo un d\u00eda nublado, en el que no notamos la radiaci\u00f3n del sol sobre nuestra cara, solemos olvidarnos de que sus efectos nocivos nos siguen llegando, m\u00e1s a\u00fan si subimos a la monta\u00f1a. Esto ocurre porque seg\u00fan aumenta la altitud, la atm\u00f3sfera aten\u00faa menos los rayos solares y, por tanto, son m\u00e1s intensos y m\u00e1s peligrosos para nuestra salud. No es necesario ascender miles de metros para tener en cuenta este hecho, ya que con tan s\u00f3lo que ascendamos 300 metros, la intensidad de la radiaci\u00f3n aumenta un cinco por ciento en comparaci\u00f3n con la que recibimos a nivel del mar. Por tanto, proteger nuestro cuerpo de esta exposici\u00f3n es si cabe m\u00e1s importante en la monta\u00f1a que en la playa, incluso en los d\u00edas nublados.<\/p>\n<h4 class=\"TituloWeb\"><strong>Efecto de la nieve<\/strong><\/h4>\n<p>A la alta radiaci\u00f3n que nos exponemos en la monta\u00f1a, hay que sumarle la posible presencia de nieve. Y es que est\u00e1 provoca una especie de &quot;efecto espejo&quot;, ya que refleja m\u00e1s del ochenta por ciento de la luz solar, incluida la radiaci\u00f3n ultravioleta. Cuando esquiamos, gracias al uso de la m\u00e1scara, este efecto no llega a nuestros ojos, pero cuando simplemente andamos en un entorno donde hay nieve no somos conscientes de este reflejo, por lo que podemos pasar varias horas recibiendo esta radiaci\u00f3n intensa en nuestros ojos, sin darnos cuenta de lo perjudicial que puede resultar.<\/p>\n<h4 class=\"TituloWeb\"><strong>Otros &quot;impedimentos&quot;<\/strong><\/h4>\n<p>En este entorno de nieve y alta monta\u00f1a, existen otros agentes que tambi\u00e9n pueden impedir que veamos correctamente e incluso que produzcan da\u00f1os en nuestros ojos:<\/p>\n<ul>\n<li>Cuando el viento impacta sobre nuestra cara favorece la sequedad ocular.<\/li>\n<li>Si el viento se combina con la presencia de nieve es muy probable que part\u00edculas y peque\u00f1os cristales de hielo entren en nuestros ojos, algo que debemos evitar porque incluso pueden da\u00f1ar la c\u00f3rnea.<\/li>\n<li>La sequedad ocular, el viento y\/o la entrada de alguna part\u00edcula en el ojo puede evitar que veamos correctamente, lo que favorece que tengamos una ca\u00edda.<\/li>\n<\/ul>\n<h4 class=\"TituloWeb\"><strong>\u00bfC\u00f3mo se resienten los ojos?<\/strong><\/h4>\n<p>De forma consciente podemos notar ciertas molestias en los ojos cuando no los protegemos adecuadamente en un ambiente ventoso y\/o con nieve. Sin embargo, los efectos de esta falta de protecci\u00f3n van m\u00e1s all\u00e1. El Consejo General de Colegios de \u00d3pticos-Optometrista indica que la radiaci\u00f3n ultravioleta acelera la aparici\u00f3n de ciertos tipos de cataratas y de la degeneraci\u00f3n macular asociada a la edad, dos de los problemas de salud ocular m\u00e1s frecuentes durante la madurez. A su vez, a corto plazo tambi\u00e9n pueden aparecer otros problemas como fotofobias, conjuntivitis, y \u00falceras que si no son tratados adecuadamente pueden derivar en problemas m\u00e1s graves. <\/p>\n<h4 class=\"TituloWeb\"><strong>Tus compa\u00f1eras de aventura<\/strong><\/h4>\n<p>Si entre tus aficiones est\u00e1 la pr\u00e1ctica de alpinismo, escalada o senderismo, debes incluir siempre en tu equipamiento unas gafas de sol adecuadas. Depender\u00e1 de la altura que asciendas y de las condiciones en las que practiques el deporte para determinar ciertas caracter\u00edsticas t\u00e9cnicas que deben tener tus gafas, pero en t\u00e9rminos generales es conveniente que:<\/p>\n<ul>\n<li>Incorporen filtro de categor\u00eda 3 e incluso 4.<\/li>\n<li>Filtren el 100% los rayos ultravioletas.<\/li>\n<li>Sean polarizadas porque adem\u00e1s de proteger de la radiaci\u00f3n ultravioleta, evitan los deslumbramientos que originan el reflejo de la luz sobre la nieve.<\/li>\n<li>Sus lentes sean de espejo para que la luz del sol se reflejen sobre ellas y no lleguen a los ojos.<\/li>\n<li>Cubran los laterales del rostro para que tambi\u00e9n protejan la piel de la zona. A su vez, al colocarlas deben quedar pr\u00f3ximas al rostro (sin que llegue a molestar) para que tampoco entren los rayos solares por la zona superior de los ojos.<\/li>\n<li>Se adapten perfectamente al rostro, algo que lo proporcionan las varillas y plaquetas nasales ajustables.<\/li>\n<li>Sean ligeras para que no te molesten al realizar cualquier movimiento.<\/li>\n<li>Sus lentes est\u00e9n dise\u00f1adas con material org\u00e1nico porque resisten mejor los golpes y las ralladuras.<\/li>\n<\/ul>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/7AFC6C75-7167-4168-8813-4171C0ADB805\/90651755-D77B-4761-A118-6DCD0A27785A\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuando nos preparamos para practicar un deporte de invierno no prescindimos del mono, los guantes, ni de la m\u00e1scara.<\/p>\n","protected":false},"featured_media":1661,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[68],"tags":[],"class_list":["post-836","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-salud-visual"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1661"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}