<!---->{"id":863,"date":"2017-03-05T00:00:00","date_gmt":"2017-03-04T23:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/menos-del-30-de-personas-con-diabetes-se-somete-a-una-revision-anual-de-la-retina\/"},"modified":"2023-01-18T01:26:00","modified_gmt":"2023-01-18T00:26:00","slug":"menos-del-30-de-personas-con-diabetes-se-somete-a-una-revision-anual-de-la-retina","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/menos-del-30-de-personas-con-diabetes-se-somete-a-una-revision-anual-de-la-retina\/","title":{"rendered":"Menos del 30 % de personas con diabetes se somete a una revisi\u00f3n anual de la retina"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">revisiondiabetes.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/89B93EC2-4F25-4C48-8314-805924740750\/Cuerpo\/revisiondiabetes.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\nA pesar de ser la primera causa de ceguera irreversible en edad laboral, curiosamente la retinopat\u00eda diab\u00e9tica es tambi\u00e9n una afecci\u00f3n visual evitable si se logra detectar y tratar a tiempo, logrando evitar la p\u00e9rdida grave de visi\u00f3n en la mayor\u00eda de los casos.<br \/>La retinopat\u00eda diab\u00e9tica afecta a la retina de los pacientes que tienen diabetes, haciendo que los vasos sangu\u00edneos que suministran sangre a la retina se lesionen por el alto nivel de az\u00facar, volvi\u00e9ndose fr\u00e1giles. Esto provoca edema o hemorragias que derivan en p\u00e9rdida de agudeza visual. Tanto las personas con&nbsp;diabetes tipo 1&nbsp;como con diabetes tipo 2&nbsp;est\u00e1n en riesgo de padecer esta afecci\u00f3n, siendo cuatro veces m\u00e1s frecuente en los diab\u00e9ticos tipo 1.<br \/>&nbsp;\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/89B93EC2-4F25-4C48-8314-805924740750\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La retinopat\u00eda diab\u00e9tica es la principal causa de ceguera en edad laboral. De hecho, el 23% de los pacientes con diabetes desarrollar\u00e1n esta patolog\u00eda 5 a\u00f1os despu\u00e9s del diagn\u00f3stico. Sin embargo, seg\u00fan datos ofrecidos por la Federaci\u00f3n Espa\u00f1ola de Diabetes solo entre un 20 y un 30% de diab\u00e9ticos se somete a una revisi\u00f3n anual de retina. <\/p>\n","protected":false},"featured_media":1688,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-863","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1688"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}