<!---->{"id":867,"date":"2021-05-24T00:00:00","date_gmt":"2021-05-23T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/como-prevenir-la-sequedad-ocular\/"},"modified":"2023-01-18T01:26:07","modified_gmt":"2023-01-18T00:26:07","slug":"como-prevenir-la-sequedad-ocular","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/como-prevenir-la-sequedad-ocular\/","title":{"rendered":"C\u00f3mo prevenir la sequedad ocular"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">eye-3805227_1920.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/08E8D48A-9785-4D62-A3F2-81CB5E338D37\/Cuerpo\/eye-3805227_1920.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>El <strong>s\u00edndrome del ojo seco es un trastorno visual producido en la superficie de la c\u00f3rnea y la conjuntiva<\/strong>. Es originado, bien porque no somos capaces de producir una cantidad de l\u00e1grimas adecuadas o porque estas no contienen la calidad suficiente para mantener la vista hidratada y sana.<\/p>\n<p>La sequedad ocular es <strong>m\u00e1s frecuente en mujeres que en hombres<\/strong>, sobre todo en aquellas que pasan la menopausia. Tambi\u00e9n puede afectar a personas que vivan en grandes ciudades con niveles de contaminaci\u00f3n atmosf\u00e9rica muy elevados o en zonas de mayor altitud. En t\u00e9rminos nacionales, uno de cada diez espa\u00f1oles, mayores de 40 a\u00f1os, padece esta molestia.<\/p>\n<p>La <strong>falta de l\u00e1grimas en los ojos es un problema porque es la encargada de nutrir, humidificar y lubricar la superficie del ojo<\/strong>. Algunos de los s\u00edntomas m\u00e1s comunes son:<\/p>\n<p>\u2022\tSensaci\u00f3n de quemaz\u00f3n<\/p>\n<p>\u2022\tSensaci\u00f3n de picor<\/p>\n<p>\u2022\tEnrojecimiento<\/p>\n<p>\u2022\tSensaci\u00f3n de arenilla<\/p>\n<p>\u2022\tMalestar al realizar tareas cotidianas (leer, conducir, fijar la vista en aparatos electr\u00f3nicos)<\/p>\n<p>\u2022\tEs posible que haya casos que experimenten visi\u00f3n borrosa o excesiva sensibilidad a la luz<\/p>\n<p>\u2022\tFatiga visual<\/p>\n<p>\u2022\tOjos llorosos<\/p>\n<p>\u2022\tInflamaci\u00f3n y dolor<br \/>\n<\/p>\n<p><strong>Causas<\/strong><\/p>\n<p>\u2022\tLa principal causa en una mala secreci\u00f3n debido a nuestra edad. Con el envejecimiento, es m\u00e1s dif\u00edcil crear l\u00e1grimas de manera constante.<\/p>\n<p>\u2022\tLas mujeres pueden sufrirlo por cuestiones hormonales como son el embarazo, el consumo de anticonceptivos orales y la menopausia.<\/p>\n<p>\u2022\tEl factor ambiental tambi\u00e9n es relevante porque puede secar el ojo: viento, aire acondicionado, calefacciones, etc.<\/p>\n<p>\u2022\tPor enfermedades sist\u00e9micas como pueden ser la artritis o lupus eritematoso.<\/p>\n<p>\u2022\tEl uso de lentes de contacto.<\/p>\n<p>\u2022\tPor enfermedades cicatrizantes de la superficie ocular (conjuntivitis v\u00edrica severa).<\/p>\n<p>Aunque no exista una cura definitiva, desde la <a href=\"https:\/\/www.funsavi.es\/inicio\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n Salud Visual<\/a> os proponemos unos consejos con los que intentar disminuir los s\u00edntomas de la sequedad ocular:<\/p>\n<p>\u2022\tEs recomendable hidratar el sistema visual a trav\u00e9s de l\u00e1grimas artificiales o gotas para aliviar la irritaci\u00f3n o las molestias oculares.<\/p>\n<p>\u2022\tDebemos dejar que nuestros ojos descansen. Forzar la vista con actividades como pueden ser ver la televisi\u00f3n, chatear con el m\u00f3vil o leer un libro son acciones que requieren de una alta intensidad. Se recomienda hacer pausas y pesta\u00f1ear con frecuencia con la que poder recuperar la humedad perdida.<\/p>\n<p>\u2022\tEl uso de gafas puede protegernos de los factores medioambientales que afectan a la lubricaci\u00f3n natural de nuestros ojos.<\/p>\n<p>\u2022\tAplicar compresas calientes sobre nuestros ojos y limpiar de una manera suave y cuidada los p\u00e1rpados con jabones espec\u00edficos que puedan eliminar el exceso de aceite que acumulan las gl\u00e1ndulas de los p\u00e1rpados.<\/p>\n<p>\u2022\tTener una dieta completa en la que se incluya alimentos ricos en Omega-3. Estos \u00e1cidos grasos los podemos encontrar en alimentos como el pescado azul (salm\u00f3n, sardinas y anchoas) y en las semillas de lino.<\/p>\n<p>La sequedad ocular es un trastorno permanente, saber estos consejos puede ayudarle a aliviar los s\u00edntomas. Si piensa que no puede controlar o bajar el dolor no dude en acudir a un especialista para dictaminar cual es el mejor tratamiento en cada caso.<br \/>\n<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/08E8D48A-9785-4D62-A3F2-81CB5E338D37\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Consejos de Funsavi para prevenir el s\u00edndrome del ojo seco o la sequedad ocular.<\/p>\n","protected":false},"featured_media":1692,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-867","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1692"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}