<!---->{"id":928,"date":"2015-04-10T10:36:00","date_gmt":"2015-04-10T08:36:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/un-estudio-aconseja-usar-solamente-el-delineador-fuera-de-los-parpados\/"},"modified":"2023-01-18T01:28:52","modified_gmt":"2023-01-18T00:28:52","slug":"un-estudio-aconseja-usar-solamente-el-delineador-fuera-de-los-parpados","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/un-estudio-aconseja-usar-solamente-el-delineador-fuera-de-los-parpados\/","title":{"rendered":"Un estudio aconseja usar solamente el delineador fuera de los p\u00e1rpados"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">355&#215;263-001.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/D5FE8498-40BE-460A-8747-A4867F4ACCB8\/Cuerpo\/355x263-001.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/D5FE8498-40BE-460A-8747-A4867F4ACCB8\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan un estudio desarrollado por investigadores del Centro de Investigaci\u00f3n de Lentes de Contacto en la Universidad de Waterloo, en Canad\u00e1, aplicar el l\u00e1piz delineador en la parte interior del p\u00e1rpado aumenta el riesgo de que determinadas part\u00edculas nocivas se pongan en contacto con la superficie del ojo y ocasionen problemas oculares y visuales de diferente gravedad. <\/p>\n<p>Durante el estudio, un grupo de mujeres voluntarias se aplicaron primero delineador con brillantina a lo largo de la l\u00ednea de las pesta\u00f1as y posteriormente en el interior del p\u00e1rpado, en una zona m\u00e1s cerca de la c\u00f3rnea. En un per\u00edodo de cinco minutos, se trasladaron a la pel\u00edcula lagrimal del ojo entre un 15% y un 30% m\u00e1s de part\u00edculas generadas por el delineador cuando este se aplic\u00f3 al p\u00e1rpado interno, comparado con las veces en las que se aplic\u00f3 en el exterior de la l\u00ednea de las pesta\u00f1as. <\/p>\n<p>Los investigadores observaron que las part\u00edculas tambi\u00e9n se trasladaron m\u00e1s r\u00e1pidamente a la superficie ocular cuando el delineador se aplic\u00f3 dentro de la l\u00ednea de las pesta\u00f1as, seg\u00fan las conclusiones enunciadas por Alison Neg, investigadora principal del estudio. <\/p>\n<p>Eso puede llevar a complicaciones, como irritaci\u00f3n y enrojecimiento ocular, y la presencia de bacterias da\u00f1inas puede provocar en primera instancia malestar, picor y visi\u00f3n borrosa producidos por la\u00a0 infecci\u00f3n \u00a0de los ojos. Los resultados se publicaron en la revista Eye and Contact Lens Science and Clinical Practice.<\/p>\n","protected":false},"featured_media":1752,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-928","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1752"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}