<!---->{"id":969,"date":"2013-04-16T12:30:00","date_gmt":"2013-04-16T10:30:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/la-fundacion-salud-visual-colaboradora-de-optom-meeting-malaga\/"},"modified":"2023-01-18T01:30:25","modified_gmt":"2023-01-18T00:30:25","slug":"la-fundacion-salud-visual-colaboradora-de-optom-meeting-malaga","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/la-fundacion-salud-visual-colaboradora-de-optom-meeting-malaga\/","title":{"rendered":"La Fundaci\u00f3n Salud Visual, colaboradora de OPTOM Meeting M\u00e1laga."},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">2.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/124A2093-4002-4E00-9DFD-BCFF991BF565\/Cuerpo\/2.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>Estas jornadas para profesionales, organizadas por el Consejo General de Colegios de \u00d3pticos-Optoometristas y el Colegio Oficial de \u00d3pticos-Optometristas de Andaluc\u00eda, cuentan con la colaboraci\u00f3n de la Fundaci\u00f3n Salud Visual.<\/p>\n<p><i>\u201cEl envejecimiento de la poblaci\u00f3n en pa\u00edses desarrollados como Espa\u00f1a, unido al aumento de la esperanza de vida, har\u00e1 que se incremente la incidencia de estas dos patolog\u00edas oculares, que, si no se detectan a tiempo, pueden provocar una p\u00e9rdida visual irreversible\u201d<\/i>, comenta Juan Carlos Mart\u00ednez Moral, presidente de la Fundaci\u00f3n Salud Visual y del Consejo General de Colegios de \u00d3pticos-Optometristas.<\/p>\n<p>La detecci\u00f3n temprana del la DMAE y el glaucoma permitir\u00eda evitar un gran n\u00famero de casos de baja visi\u00f3n y ceguera. En este sentido, los datos de prevalencia hablan por s\u00ed solos: se calcula que alrededor de <b>un mill\u00f3n de espa\u00f1oles padecen glaucoma en Espa\u00f1a, aunque la mitad de ellos lo desconoce, mientras que la DMAE afecta a m\u00e1s del 7% de personas mayores de 75 a\u00f1os.<\/b><\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"http:\/\/www.malaga2013.com\">www.malaga2013.com<\/a><\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/124A2093-4002-4E00-9DFD-BCFF991BF565\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el lema \u201cVisi\u00f3n y edad, \u00bfqu\u00e9 cambios se dan?\u201d, las jornadas de OPTOM Meeting M\u00e1laga, que se desarrollar\u00e1n del 18 al 20 de abril, abordar\u00e1n la relaci\u00f3n entre la visi\u00f3n y el envejecimiento, haciendo un especial hincapi\u00e9 en la Degeneraci\u00f3n Macular Asociada a la Edad (DMAE) y el glaucoma, patolog\u00edas responsables de un elevado porcentaje de casos de ceguera y baja visi\u00f3n.<\/p>\n","protected":false},"featured_media":1793,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-969","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1793"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}