<!---->{"id":974,"date":"2017-05-19T00:00:00","date_gmt":"2017-05-18T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/exito-de-la-accion-solidaria-de-funsavi-con-refugiados-durante-optom-meeting-barcelona\/"},"modified":"2023-01-18T01:30:40","modified_gmt":"2023-01-18T00:30:40","slug":"exito-de-la-accion-solidaria-de-funsavi-con-refugiados-durante-optom-meeting-barcelona","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/exito-de-la-accion-solidaria-de-funsavi-con-refugiados-durante-optom-meeting-barcelona\/","title":{"rendered":"\u00c9xito de la acci\u00f3n solidaria de FUNSAVI con refugiados durante OPTOM Meeting Barcelona"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">Examenvisualaunrefug.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/35523B6D-AC5B-4C1A-BDBD-C082AB7512C4\/Cuerpo\/Examenvisualaunrefug.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\nLa Fundaci\u00f3n Salud Visual (FUNSAVI,) auspiciada por el Colegio Nacional de \u00d3pticos-Optometristas (CNOO), se acerc\u00f3 una vez m\u00e1s a los refugiados que viven en distintas zonas geogr\u00e1ficas de Espa\u00f1a, aportando todos sus conocimientos cient\u00edfico-sanitarios y soluciones oft\u00e1lmicas en pro de su salud visual y una mejor calidad de vida. En esta ocasi\u00f3n, el s\u00e1bado 13 de mayo, en el marco del programa \u201cFunsavi Social\u201d y englobado en el desarrollo del congreso OPTOM Meeting Barcelona, un equipo de profesionales \u00f3pticos-optometristas, algunos de ellos repitiendo su acci\u00f3n como voluntarios para esta misma causa, se desplazaron hasta la Ciudad Condal para participar en esta importante iniciativa solidaria que, sin duda, ha sido muy importante para la salud visual de los refugiados.<br \/>&nbsp;\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/35523B6D-AC5B-4C1A-BDBD-C082AB7512C4\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de OPTOM Meeting Barcelona, que se desarroll\u00f3 los d\u00edas 12 al 14 de mayo en el Hotel Barcel\u00f3 Sants, con m\u00e1s de 750 participantes, la Fundaci\u00f3n Salud Visual auspici\u00f3 el s\u00e1bado 13 de mayo una acci\u00f3n solidaria realizando ex\u00e1menes visuales a refugiados de distintas zonas geogr\u00e1ficas del mundo.<\/p>\n","protected":false},"featured_media":1798,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-974","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1798"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=974"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=974"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}