<!---->{"id":983,"date":"2013-06-03T09:17:00","date_gmt":"2013-06-03T07:17:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/ya-esta-disponible-la-nueva-revista-consejos-de-la-fundacion-salud-visual-desarrollo-optometrico-y-audiologico\/"},"modified":"2023-01-18T01:31:00","modified_gmt":"2023-01-18T00:31:00","slug":"ya-esta-disponible-la-nueva-revista-consejos-de-la-fundacion-salud-visual-desarrollo-optometrico-y-audiologico","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/ya-esta-disponible-la-nueva-revista-consejos-de-la-fundacion-salud-visual-desarrollo-optometrico-y-audiologico\/","title":{"rendered":"Ya est\u00e1 disponible la nueva revista Consejos de la Fundaci\u00f3n Salud Visual, Desarrollo Optom\u00e9trico y Audiol\u00f3gico"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">portada.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/D9144A83-3367-4807-85FD-C53B12B5E63E\/Cuerpo\/portada.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>La nueva revista Consejos de la Fundaci&oacute;n Salud Visual, Desarrollo Optom&eacute;trico y Audiol&oacute;gico ya est&aacute; en las &oacute;pticas. En sus p&aacute;ginas encontrar&aacute;s la informaci&oacute;n m&aacute;s &uacute;til para cuidar tu visi&oacute;n, presentada de una forma amena y atractiva, as&iacute; como las &uacute;ltimas novedades de moda en gafas graduadas y de sol. &nbsp; <\/p>\n<p>&iquest;En qu&eacute; debemos fijarnos para que unas monturas nos sienten bien? &iquest;El &oacute;ptico-optometrista puede adaptarnos unas gafas espec&iacute;ficas para trabajar frente al ordenador? &iquest;Qu&eacute; opciones est&aacute;n disponibles a la hora de corregir la miop&iacute;a? &iquest;Realmente los auriculares pueden da&ntilde;ar nuestros o&iacute;dos? Este n&uacute;mero de Consejos de la Fundaci&oacute;n Salud Visual, Desarrollo Optom&eacute;trico y Audiol&oacute;gico responde a estas y otras preguntas, adem&aacute;s de despejar otras dudas y curiosidades en la secci&oacute;n &ldquo;Consultas de los lectores&rdquo;. &nbsp; <\/p>\n<p>Y si quer&eacute;is estar a la &uacute;ltima, no te pierdas las propuestas de moda en monturas de graduado y gafas de sol. Esta temporada primavera-verano se llevan los dise&ntilde;os elegantes pero con sutiles combinaciones de tonos. En caso de que quieras estrenar gafas de sol, en Consejos encontrar&aacute;s modelos tan variados que no te podr&aacute;s decidir solo por uno. &nbsp; <\/p>\n<p>En definitiva, &iexcl;no esperes m&aacute;s y busca ya en tu &oacute;ptica el nuevo n&uacute;mero de Consejos de la Fundaci&oacute;n Salud Visual, Desarrollo Optom&eacute;trico y Audiol&oacute;gico!<\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/D9144A83-3367-4807-85FD-C53B12B5E63E\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La nueva revista Consejos de la Fundaci\u00f3n Salud Visual, Desarrollo Optom\u00e9trico y Audiol\u00f3gico ya est\u00e1 en las \u00f3pticas. En sus p\u00e1ginas encontrar\u00e1s la informaci\u00f3n m\u00e1s \u00fatil para cuidar tu visi\u00f3n, presentada de una forma amena y atractiva, as\u00ed como las \u00faltimas novedades de moda en gafas graduadas y de sol.<\/p>\n","protected":false},"featured_media":1807,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-983","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1807"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}