<!---->{"id":991,"date":"2017-02-09T00:00:00","date_gmt":"2017-02-08T23:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/la-promocion-de-la-salud-ocular-y-visual-que-se-realiza-en-paises-en-desarrollo-no-es-eficaz\/"},"modified":"2023-01-18T01:31:16","modified_gmt":"2023-01-18T00:31:16","slug":"la-promocion-de-la-salud-ocular-y-visual-que-se-realiza-en-paises-en-desarrollo-no-es-eficaz","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/la-promocion-de-la-salud-ocular-y-visual-que-se-realiza-en-paises-en-desarrollo-no-es-eficaz\/","title":{"rendered":"La promoci\u00f3n de la salud ocular y visual que se realiza en pa\u00edses en desarrollo no es eficaz"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">promociondelasaludoc.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/00257786-8C54-457C-87EA-CAF60726375E\/Cuerpo\/promociondelasaludoc.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>La informaci\u00f3n proveniente de la investigaci\u00f3n sobre lo que un p\u00fablico objetivo piensa, sabe y hace sobre una preocupaci\u00f3n particular de salud conduce al desarrollo de la estrategia de educaci\u00f3n para la salud, incluyendo el establecimiento y la naturaleza de la intervenci\u00f3n. Los materiales deben ser desarrollados y probados experimentalmente, para asegurar que los mensajes sean interpretados y entendidos correctamente por el p\u00fablico a quien nos dirigimos.<\/p>\n<p>Por todo ello, la evaluaci\u00f3n es esencial para la expansi\u00f3n de la promoci\u00f3n de la salud ocular. La evaluaci\u00f3n debe proporcionar la informaci\u00f3n y la retroalimentaci\u00f3n para hacer mejoras en las actividades futuras. Si bien el objetivo final es mejorar la salud ocular, es \u00fatil incorporar indicadores intermedios, tales como mayor conciencia, cambio de comportamiento, habilidades, autoeficacia, cobertura y calidad de los servicios y adopci\u00f3n de pol\u00edticas espec\u00edficas.<\/p>\n<p>Muchos de los principios de la promoci\u00f3n efectiva de la salud ocular surgen de las evaluaciones de la Base de Datos sobre Educaci\u00f3n Sanitaria del Reino Unido. Si bien ahora hay una buena gama de ejemplos evaluados para muchos temas de salud, el n\u00famero de intervenciones publicadas espec\u00edficamente relacionadas con la promoci\u00f3n de la salud ocular son decepcionantes.<\/p>\n<p>Encontramos brechas notables, como la ausencia de evaluaciones publicadas que consideran el papel de la promoci\u00f3n de la salud para las principales condiciones de ceguera como en cataratas, glaucoma, retinopat\u00eda diab\u00e9tica y traumas en los pa\u00edses en desarrollo<\/p>\n<p>Un reto importante es documentar estas experiencias in\u00e9ditas sobre promoci\u00f3n de la salud visual y ocular para que la base de investigaci\u00f3n est\u00e9 abierta al escrutinio y para que las lecciones aprendidas puedan ser incorporadas en la base a la evidencia para la promoci\u00f3n de la salud ocular. <\/p>\n<p><\/p>\n<p>Fuente: <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC1856969\/\">goo.gl\/0qP7ur<\/a><\/p>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/00257786-8C54-457C-87EA-CAF60726375E\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Para la obtenci\u00f3n de \u00e9xitos, la promoci\u00f3n de la salud debe basarse en una comprensi\u00f3n detallada de lo que es en s\u00ed la salud. La contribuci\u00f3n vital de los datos cualitativos y cuantitativos a la planificaci\u00f3n de una estrategia de promoci\u00f3n de la salud es esencial a la hora de desarrollar proyectos o campa\u00f1as de promoci\u00f3n de la salud en general, ya que cada comunidad plantea sus propios desaf\u00edos y oportunidades.<\/p>\n","protected":false},"featured_media":1815,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-991","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1815"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}