<!---->{"id":992,"date":"2019-06-12T00:00:00","date_gmt":"2019-06-11T22:00:00","guid":{"rendered":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/consejos-para-que-tus-lentillas-tengan-mas-duracion\/"},"modified":"2023-01-18T01:31:18","modified_gmt":"2023-01-18T00:31:18","slug":"consejos-para-que-tus-lentillas-tengan-mas-duracion","status":"publish","type":"informaciones","link":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/informaciones\/consejos-para-que-tus-lentillas-tengan-mas-duracion\/","title":{"rendered":"Consejos para que tus lentillas tengan m\u00e1s duraci\u00f3n"},"content":{"rendered":"<div class=\"contenido__informaciones\">\n<div class=\"imagen__cuerpo__hidden hidden\">funsavi-normal.jpg<\/div>\n<div class=\"ruta__archivo__hidden hidden\"><\/div>\n<p><img decoding=\"async\" class=\"imagen__cuerpo__informacion\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/6E15A41C-2F63-47D3-A1DF-CCA0FBB9F76A\/Cuerpo\/funsavi-normal.jpg\" \/><\/p>\n<div class=\"texto__cuerpo__informacion\">\n<p>El <a href=\"https:\/\/www.funsavi.es\/lentes-de-contacto\/por-que-usar-lentes-de-contacto\" target=\"_blank\" rel=\"noopener\">uso de lentillas<\/a> aporta comodidad al usuario respecto a la utilizaci\u00f3n de gafas. En este sentido, existen diferentes tipos, como las mensuales, las diarias, blandas o r\u00edgidas, entre otras modalidades. Sin embargo, para un empleo adecuado es necesario seguir ciertos pasos con los que conseguiremos prolongar su duraci\u00f3n. <\/p>\n<p>Estos consejos que te facilitamos desde la <a href=\"https:\/\/www.funsavi.es\/inicio\" target=\"_blank\" rel=\"noopener\">Fundaci\u00f3n Salud Visual<\/a> te ser\u00e1n de utilidad si quieres que la calidad y la durabilidad de tus lentillas se mantengan durante mucho tiempo y las veas igual de impecables que en el primer d\u00eda.\n<\/p>\n<ul>\n<li><strong>Manipula las lentes de contacto siempre con las manos limpias<\/strong>. Adem\u00e1s, es necesario mantener una higiene determinada para no ensuciarlas.<\/li>\n<li><strong>Mant\u00e9n el dep\u00f3sito de lentillas limpio diariamente con la soluci\u00f3n desinfectante recomendada<\/strong> por tu \u00f3ptico-optometrista, as\u00ed evitar\u00e1s que se rompan o se resequen.&nbsp;<\/li>\n<li>Reemplaza el estuche en el que sueles guardarlas una vez cada tres meses.<\/li>\n<li><span style=\"text-align: justify;\"><strong>Intenta no dormir con ellas puestas<\/strong>, ya que esto puede hacer que el ojo se reseque y provocar conjuntivitis. Del mismo modo, las lentillas pueden estropearse de manera m\u00e1s f\u00e1cil al hacer un mal uso.<\/span><\/li>\n<li><span style=\"text-align: justify;\">Tambi\u00e9n se recomienda <strong>descansar un d\u00eda a la semana, alternando con el uso de gafas<\/strong>, aunque algunas lentillas est\u00e1n dise\u00f1adas para su uso diario sin necesidad de recurrir al descanso.<\/span><\/li>\n<li><span style=\"text-align: justify;\"><strong>Intenta no manipularlas con las u\u00f1as<\/strong>, ya que esto las deteriorar\u00e1 y posiblemente las rompa.<\/span><\/li>\n<li><span style=\"text-align: justify;\"><strong>Impide que el maquillaje entre en el ojo<\/strong> y perjudique a la lentilla.<\/span><\/li>\n<li><span style=\"text-align: justify;\"><strong>Si vas a nadar, procura no abrir los ojos a la hora de bucear<\/strong> sin gafas acu\u00e1ticas. Esta situaci\u00f3n podr\u00eda provocar que las lentillas se salgan y se pierdan. En casos m\u00e1s graves, implicar\u00eda una posible infecci\u00f3n ocular.<\/span><\/li>\n<li><span style=\"text-align: justify;\">Si las lentes de contacto te parecen inc\u00f3modas, <strong>no las manipules con las manos sucias<\/strong> y aseg\u00farate de que te las has puesto correctamente.<\/span><\/li>\n<li><span style=\"text-align: justify;\">Est\u00e1 <strong>contraindicado el uso de lentillas caducadas<\/strong>. Antes de su empleo, revisa bien el envase para intentar no caer en este error. La fecha de caducidad representa el tiempo que permanecer\u00e1n esterilizadas, por lo que pueden resultar inc\u00f3modas y peligrosas a partir de que excedan ese l\u00edmite.&nbsp;<\/span><\/li>\n<li><span style=\"text-align: justify;\"><strong>No compartas tus lentillas con nadie<\/strong>. Aunque parezca il\u00f3gico, es importante que su uso sea totalmente personal, ya que la transmisi\u00f3n de infecciones puede ser m\u00e1s probable si las compartes.<\/span><\/li>\n<li><span style=\"text-align: justify;\">Por \u00faltimo, <strong>no uses la saliva, el agua del grifo o remedios caseros<\/strong> como sustitutivos del l\u00edquido espec\u00edfico de las lentillas. Es importante que solo utilices la soluci\u00f3n recomendada por tu \u00f3ptico-optometrista.&nbsp;<\/span><\/li>\n<\/ul>\n<div style=\"text-align: justify;\"><span style=\"font-family: &quot;Trebuchet MS&quot;, Arial, Verdana; color: #333333;\"><span style=\"font-size: 13px;\">Sigue estos consejos para evitar que tu ojo sufra alg\u00fan da\u00f1o. Si usas lentes que no se ajustan bien a tu forma ocular, pueden crecer vasos sangu\u00edneos en la c\u00f3rnea, provocando un riesgo para la visi\u00f3n. Asimismo, si tienes tendencias a las infecciones oculares, <a href=\"https:\/\/www.funsavi.es\/actualidad\/el-optico-optometrista-clave-para-deteccion-y-mejora-visual-de-pacientes-con-retinopatia-diabetica-3\" target=\"_blank\" rel=\"noopener\">visita a tu \u00f3ptico-optometrista de confianza<\/a> para que te recomiende unas lentillas adaptadas a tus necesidades.&nbsp;<\/span><\/span><\/div>\n<\/div>\n<div id=\"bloque__descargas__descarga\" class=\"bloque__descargas__descarga clear-both p-4 mb-2 mt-4 rounded border border-solid border-zinc-300\">\n<h2 class=\"p-0 my-2 mx-0 text-3xl leading-8 text-sky-800\">M\u00e1s informaci\u00f3n<\/h2>\n<div class=\"grid sm:grid-cols-[1fr_170px] gap-4 items-flex-start mb-4\">\n<div class=\"grid grid-cols-[32px_1fr] gap-4 items-center\">\n<div class=\"w-8\">\n                <img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/pdf.gif\" width=\"32\">\n            <\/div>\n<p id=\"texto__documento__boton__descargas\" class=\"texto__documento__boton__descargas mb-0\">\n<\/p><\/div>\n<p>            <a target=\"\u201d_blank\u201d\" download id=\"enlace__descarga__bloque__descargas\" class=\"enlace__descarga__bloque__descargas flex gap-4 justify-between h-fit float-right ml-auto py-2 pr-4 pl-4 m-0 text-white align-middle bg-no-repeat rounded-lg border-t border-solid cursor-pointer border-slate-50 bg-sky-800 hover:border-zinc-800 hover:bg-zinc-800 hover:bg-no-repeat hover:text-stone-300\" href=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/Documentos\/informaciones\/1CA9B394-5766-45F4-BB08-7915772FCAB3\/6E15A41C-2F63-47D3-A1DF-CCA0FBB9F76A\/\/\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/wp-content\/uploads\/2022\/10\/Descargar.png\"\/> Descargar<\/a>\n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Unos sencillos trucos y recomendaciones para que tus lentillas duren el m\u00e1ximo tiempo posible y funcionen correctamente.<\/p>\n","protected":false},"featured_media":1816,"template":"","meta":{"_crosspost_to_1":true,"_crosspost_to_8":false,"_crosspost_to_9":false,"_crosspost_to_10":false,"_crosspost_to_11":false,"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"categories":[34],"tags":[],"class_list":["post-992","informaciones","type-informaciones","status-publish","has-post-thumbnail","hentry","category-noticias-ciudadanos"],"acf":[],"_links":{"self":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones\/992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/informaciones"}],"about":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/types\/informaciones"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media\/1816"}],"wp:attachment":[{"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/media?parent=992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/categories?post=992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pedantic-sammet.185-14-57-205.plesk.page\/funsavi\/wp-json\/wp\/v2\/tags?post=992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}